{"id":97463,"date":"2020-01-28T13:22:07","date_gmt":"2020-01-28T16:22:07","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/concurso-por-cargo\/arquiteto\/"},"modified":"2020-09-30T21:24:16","modified_gmt":"2020-10-01T00:24:16","slug":"arquiteto","status":"publish","type":"concurso_por_cargo","link":"https:\/\/www.novaconcursos.com.br\/portal\/concurso-por-cargo\/arquiteto\/","title":{"rendered":"Concursos para Arquiteto"},"content":{"rendered":"<p>Em busca de <strong>concursos para Arquiteto<\/strong>? Aqui listamos todos os <a rel=\"noreferrer noopener\" aria-label=\"certames (abre numa nova aba)\" href=\"https:\/\/www.novaconcursos.com.br\" target=\"_blank\">certames<\/a> para voc\u00ea atingir seu objetivo. Confira j\u00e1 todas as <a rel=\"noreferrer noopener\" href=\"https:\/\/www.novaconcursos.com.br\/\" target=\"_blank\">oportunidades<\/a> em busca da sua realiza\u00e7\u00e3o profissional. <\/p>\n\n\n\n<p>O cargo de Arquiteto tem o requisito de <strong>n\u00edvel superior de escolaridade<\/strong>, na respectiva \u00e1rea. Suas <strong>atribui\u00e7\u00f5es<\/strong> s\u00e3o: supervis\u00e3o, coordena\u00e7\u00e3o, gest\u00e3o e orienta\u00e7\u00e3o t\u00e9cnica; coleta de dados, estudo, planejamento, projeto e especifica\u00e7\u00e3o; estudo de viabilidade t\u00e9cnica e ambiental; assist\u00eancia t\u00e9cnica, assessoria e consultoria; dire\u00e7\u00e3o de obras e de servi\u00e7o t\u00e9cnico, dentre outros.<\/p>","protected":false},"featured_media":0,"template":"","class_list":["post-97463","concurso_por_cargo","type-concurso_por_cargo","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/concurso_por_cargo\/97463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/concurso_por_cargo"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/concurso_por_cargo"}],"version-history":[{"count":2,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/concurso_por_cargo\/97463\/revisions"}],"predecessor-version":[{"id":106810,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/concurso_por_cargo\/97463\/revisions\/106810"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=97463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}