{"id":150672,"date":"2021-12-13T10:28:35","date_gmt":"2021-12-13T13:28:35","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=150672"},"modified":"2021-12-14T08:09:41","modified_gmt":"2021-12-14T11:09:41","slug":"concurso-seduc-pi-novo-edital-estudo","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-seduc-pi-novo-edital-estudo\/","title":{"rendered":"Concurso Seduc PI: Novo edital em estudo, diz secret\u00e1rio!"},"content":{"rendered":"<p>Boas not\u00edcias para os concurseiros! Um novo <strong>concurso Seduc PI<\/strong> est\u00e1 em estudo, de acordo com o secret\u00e1rio estadual de educa\u00e7\u00e3o do estado. Ademais, o primeiro passo ser\u00e1 uma <strong>an\u00e1lise das necessidades da \u00e1rea.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Confira: <\/strong><a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/guia-definitivo-plano-de-estudos-passo-a-passo\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Guia Definitivo Plano de Estudos \u2013 Gr\u00e1tis<\/a><\/li><\/ul><p><\/p>\n\n\n\n<p>Na \u00faltima ter\u00e7a-feira, <strong>7 de dezembro de 2021<\/strong>, o secret\u00e1rio estadual de educa\u00e7\u00e3o Ellen Gera comunicou em uma reuni\u00e3o que ser\u00e3o realizados <strong>estudos para um novo concurso<\/strong> da Secretaria de Educa\u00e7\u00e3o e Cultura do <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-previstos\/pi\/\">Piau\u00ed<\/a>. Ademais, o que se prev\u00ea s\u00e3o oportunidades para <strong>Professores.<\/strong><\/p>\n\n\n\n<p>Al\u00e9m disso, a reuni\u00e3o citada contou tamb\u00e9m com a presen\u00e7a do Sindicato dos Trabalhadores da Educa\u00e7\u00e3o do Piau\u00ed (Sinte) e de representantes do Governo para as <strong>\u00e1reas administrativa e financeira<\/strong>, de forma que tamb\u00e9m foi discutida a quest\u00e3o do aumento salarial de <strong>8,84% em 2022.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-seduc-pi-novo-edital\"><strong>Concurso Seduc PI: novo edital<\/strong><\/h2>\n\n\n\n<p>Sendo assim, ser\u00e3o realizados estudos para a abertura de um <strong>novo edital para Professores<\/strong> no <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/pi\/\">Piau\u00ed<\/a>. Ademais, segundo o secret\u00e1rio Gera, a sele\u00e7\u00e3o \u00e9 importante para suprir as necessidades geradas pela <strong>implementa\u00e7\u00e3o do Novo Ensino M\u00e9dio e de outros programas:<\/strong><\/p>\n\n\n\n<p><em>\u201cEstamos fazendo um estudo\ninterno sobre as novas demandas da educa\u00e7\u00e3o, avaliando as necessidades que\nsurgiram com o Novo Ensino M\u00e9dio, com a educa\u00e7\u00e3o profissional e com os\nprogramas de alfabetiza\u00e7\u00e3o em regime de colabora\u00e7\u00e3o com os munic\u00edpios e, a\npartir dessa an\u00e1lise, poderemos realizar um concurso p\u00fablico para professores\u201d,<\/em>\ndisse.<\/p>\n\n\n\n<p>Al\u00e9m disso, a proposta do novo concurso Seduc PI ainda dever\u00e1 ser aprovada pela <strong>Assembleia Legislativa<\/strong> do estado, de forma que, posteriormente, uma <strong>comiss\u00e3o organizadora<\/strong> dever\u00e1 ser formada para que os tr\u00e2mites sejam iniciados.<\/p>\n\n\n\n<p>Ademais, o grupo tamb\u00e9m ser\u00e1 respons\u00e1vel pelo processo de <strong>escolha e contrata\u00e7\u00e3o de uma banca<\/strong> organizadora, que cuidar\u00e1 das inscri\u00e7\u00f5es no processo seletivo, bem como da aplica\u00e7\u00e3o das etapas avaliativas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-para-educao-ser-realizado-em-teresina\"><strong>Concurso para Educa\u00e7\u00e3o ser\u00e1 realizado em Teresina<\/strong><\/h2>\n\n\n\n<p>\u00c9 igualmente importante destacar que um <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-prefeitura-de-teresina-pi\/\">concurso<\/a> para a <strong>educa\u00e7\u00e3o <\/strong>tamb\u00e9m ser\u00e1 realizado na capital do Piau\u00ed, em Teresina. Ademais, a sele\u00e7\u00e3o <strong>j\u00e1 foi autorizada<\/strong> para o provimento de <strong>1.141 oportunidades.<\/strong><\/p>\n\n\n\n<p><em>\u201cTemos um compromisso com\na educa\u00e7\u00e3o de Teresina. \u00c9 somente atrav\u00e9s da educa\u00e7\u00e3o que daremos uma vida\nmelhor para todas as pessoas que moram na nossa cidade. J\u00e1 autorizei a forma\u00e7\u00e3o\nde uma comiss\u00e3o para fazer todas as tratativas sobre o processo do\nconcurso\u201d,<\/em> disse o prefeito Dr. Pessoa.<\/p>\n\n\n\n<p>Al\u00e9m disso, 1.114 das vagas estar\u00e3o destinadas ao cargo de <strong>Professor<\/strong>, enquanto que as restantes 27 oportunidades s\u00e3o para <strong>Psic\u00f3logos, Assistentes Sociais e Nutricionistas.<\/strong><\/p>\n\n\n\n<p>Ademais, os n\u00edveis de escolaridade exigidos ser\u00e3o o <strong>m\u00e9dio, a licenciatura e a gradua\u00e7\u00e3o na \u00e1rea<\/strong>, a depender do cargo escolhido pelo candidato. Por outro lado, as remunera\u00e7\u00f5es ser\u00e3o de <strong>R$2,4 mil para 20 horas semanais<\/strong> de jornada de trabalho e <strong>R$4,8 mil para 40 horas semanais.<\/strong><\/p>\n\n\n\n<p>Sendo assim, conhe\u00e7a as \u00e1reas destinadas ao cargo de <strong>Professor:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Religi\u00e3o;<\/li><li>Educa\u00e7\u00e3o Art\u00edstica;<\/li><li>Educa\u00e7\u00e3o F\u00edsica;<\/li><li>Portugu\u00eas;<\/li><li>Matem\u00e1tica;<\/li><li>Qu\u00edmica; e<\/li><li>Geografia.<\/li><\/ul><p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ltimo-concurso-seduc-pi\"><strong>\u00daltimo concurso Seduc PI<\/strong><\/h2>\n\n\n\n<p>Por fim, \u00e9 importante destacar que o \u00faltimo concurso Seduc PI aconteceu <strong>em 2018<\/strong>, quando foram ofertadas vagas para <strong>forma\u00e7\u00e3o de cadastro reserva <\/strong>para o cargo de <strong>Professor,<\/strong> em diversas especialidades.<\/p>\n\n\n\n<p>Ademais, tamb\u00e9m foram disponibilizadas oportunidades para <strong>T\u00e9cnico<\/strong> <strong>de n\u00edvel superior<\/strong>, nas especialidades de Fonoaudi\u00f3logo, Psicomotricista e Bibliotec\u00e1rio. A <strong>organiza\u00e7\u00e3o<\/strong> se deu por parte do <a rel=\"noreferrer noopener\" aria-label=\"Nucepe (abre numa nova aba)\" href=\"https:\/\/nucepe.uespi.br\/\" target=\"_blank\">Nucepe<\/a>.<\/p>\n\n\n\n<p>Al\u00e9m disso, os candidatos do concurso foram avaliados por meio de <strong>prova objetiva, prova discursiva e avalia\u00e7\u00e3o de t\u00edtulos<\/strong>, de forma que para a prova objetiva deveriam responder a <strong>40 quest\u00f5es<\/strong> sobre Conhecimentos B\u00e1sicos e Espec\u00edficos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Boas not\u00edcias para os concurseiros! Um novo concurso Seduc PI est\u00e1 em estudo, de acordo com o secret\u00e1rio estadual de educa\u00e7\u00e3o do estado. Ademais, o primeiro passo ser\u00e1 uma an\u00e1lise das necessidades da \u00e1rea. Confira: Guia Definitivo Plano de Estudos \u2013 Gr\u00e1tis Na \u00faltima ter\u00e7a-feira, 7 de dezembro de 2021, o secret\u00e1rio estadual de educa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":54674,"featured_media":150763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[38826,6380,44553,44557,44551,44552,44558,44554,44555,20771,198,40266,38400,38827,44556],"class_list":["post-150672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-cargos-concursos-piaui","tag-concurso-seduc-pi","tag-concurso-seduc-pi-2022","tag-concurso-seduc-pi-etapas","tag-concurso-seduc-pi-previsto","tag-concurso-seduc-pi-professor","tag-concurso-seduc-pi-provas","tag-concurso-seduc-piaui","tag-concurso-seduc-piaui-previsto","tag-concursos-piaui","tag-concursos-previstos","tag-concursos-previstos-2022","tag-concursos-previstos-piaui","tag-salarios-concursos-piaui","tag-ultimo-concurso-seduc-pi"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/150672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54674"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=150672"}],"version-history":[{"count":4,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/150672\/revisions"}],"predecessor-version":[{"id":150684,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/150672\/revisions\/150684"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/150763"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=150672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=150672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=150672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}