{"id":155240,"date":"2022-02-10T09:33:40","date_gmt":"2022-02-10T12:33:40","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=155240"},"modified":"2022-02-10T15:40:07","modified_gmt":"2022-02-10T18:40:07","slug":"concurso-pc-rj-locais-prova-investigador-disponiveis","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-pc-rj-locais-prova-investigador-disponiveis\/","title":{"rendered":"Concurso PC RJ: Locais de prova para Investigador dispon\u00edveis!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aten\u00e7\u00e3o concurseiros! As\u00a0<strong>provas\u00a0<\/strong>do\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-policia-civil-rj\/\">Concurso PC RJ<\/a>\u00a0(Pol\u00edcia Civil do Rio de Janeiro), para <strong>Investigador<\/strong> ser\u00e3o aplicadas no pr\u00f3ximo domingo,\u00a0<strong>13 de fevereiro.<\/strong>\u00a0Confira os locais de prova!\u00a0<strong>S\u00e3o 200 vagas!<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Confira:<\/strong>\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/curso-gratis-pc-rj\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Curso Gr\u00e1tis Pol\u00edcia Civil RJ (Gr\u00e1tis)<\/a><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estude para o concurso dos seus sonhos com a\u00a0<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\">Assinatura Completa da Nova<\/a>. Tenha acesso a Cursos, Plataforma de Quest\u00f5es, Eventos Exclusivos para Assinantes e Muito Mais!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-pc-tj-provas-para-investigador-nesta-semana-confira\">Concurso PC TJ: provas para Investigador nesta semana; confira<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">As provas do concurso da Pol\u00edcia Civil do <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/rj\/\">Rio de Janeiro<\/a>, para o cargo de <strong>Investigador<\/strong>, ser\u00e3o aplicadas no<strong> fim desta semana.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Adquira<\/strong>:\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pc-rj-policia-civil-do-rio-de-janeiro\/curso-online\">Apostila Concurso PC RJ<\/a><\/li><li><strong>Adquira<\/strong>:\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pc-rj-policia-civil-do-rio-de-janeiro\/apostila?promo_creative=Curso+Online+PC+RJ&amp;promo_name=noticia&amp;promo_id=%2Fportal%2Fnoticias%2Fconcurso-pc-rj-mais-165-mil-inscricoes&amp;promo_position=corpo-texto\">Curso Online PC<\/a><a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pc-rj-policia-civil-do-rio-de-janeiro\/apostila\"> <\/a><a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pc-rj-policia-civil-do-rio-de-janeiro\/apostila?promo_creative=Curso+Online+PC+RJ&amp;promo_name=noticia&amp;promo_id=%2Fportal%2Fnoticias%2Fconcurso-pc-rj-mais-165-mil-inscricoes&amp;promo_position=corpo-texto\">RJ<\/a><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, no pr\u00f3ximo domingo,<strong> 13 de fevereiro<\/strong>, os candidatos disputar\u00e3o as 200 vagas que est\u00e3o sendo ofertadas para a carreira. S\u00e3o mais de <strong>120.000 mil inscritos. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Locais de prova<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, os candidatos j\u00e1 podem, inclusive, consultar os <strong>locais de realiza\u00e7\u00e3o da prova objetiva<\/strong> para o cargo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, a <strong>consulta <\/strong>deve ser realizada pela <strong>p\u00e1gina <\/strong>da <strong>banca <\/strong>organizadora, a <a href=\"https:\/\/www50.fgv.br\/ConsultaLocalProva.aspx?key=158\" target=\"_blank\" rel=\"noopener\">Funda\u00e7\u00e3o Get\u00falio Vargas<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hor\u00e1rios<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A banca afirmou que as provas ser\u00e3o <strong>aplicadas das 12h \u00e0s 17h<\/strong>. Al\u00e9m disso, \u00e9 importante ressaltar que os candidatos devem chegar com <strong>anteced\u00eancia <\/strong>ao local de prova. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, a entrada ser\u00e1 realizada de acordo com a primeira letra do nome: <strong>10h30 \u2013 A a H<\/strong>; <strong>10h50 \u2013 I a P<\/strong>; <strong>11h10 \u2013 Q a Z<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, a banca ainda deixou claro que os <strong>port\u00f5es ser\u00e3o fechados <\/strong>impreterivelmente \u00e0s 11h45.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como ser\u00e3o as provas?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, a prova objetiva ser\u00e1 <strong>composta por 100 quest\u00f5es.<\/strong> Sendo assim, ser\u00e3o cobradas as seguintes disciplinas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>L\u00edngua portuguesa \u2013 30 quest\u00f5es <\/li><li>Conhecimentos Espec\u00edficos \u2013 60 quest\u00f5es <\/li><li>Conhecimentos B\u00e1sicos de Inform\u00e1tica \u2013 10 quest\u00f5es<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, a prova ser\u00e1 de m\u00faltipla escolha, <strong>tendo 5 alternativas<\/strong> e sendo que apenas uma \u00fanica resposta ser\u00e1 a correta!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Outras etapas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os inscritos no concurso da Pol\u00edcia Civil do Rio de Janeiro ainda ser\u00e3o avaliados por meio de <strong>outras etapas de sele\u00e7\u00e3o<\/strong>, fora a objetiva. Sendo assim, s\u00e3o elas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Prova de capacidade f\u00edsica;<\/li><li>Exame psicot\u00e9cnico;<\/li><li>Exame m\u00e9dico;<\/li><li>Curso de forma\u00e7\u00e3o;<\/li><li>Prova de investiga\u00e7\u00e3o social.<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Informa\u00e7\u00f5es<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Informa\u00e7\u00f5es sobre o concurso p\u00fablico para a Pol\u00edcia Civil do Estado do Rio de Janeiro\u00a0podem ser obtidas pelo telefone\u00a0<strong>0800 2834628<\/strong>\u00a0e pelo e-mail <a href=\"mailto:concursopcrj21@fgv.br\">concursopcrj21@fgv.br<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-pc-rj-requisitos-e-salrios-para-o-cargo-de-investig\">Concurso PC RJ: requisitos e sal\u00e1rios para o cargo de Investigador<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para ser um Investigador de Pol\u00edcia Civil no <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-previstos\/rj\/\">Rio de Janeiro<\/a> \u00e9 necess\u00e1rio ter forma\u00e7\u00e3o de <strong>n\u00edvel m\u00e9dio.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, \u00e9 preciso ainda idade m\u00ednima de <strong>18 anos<\/strong> e carteira nacional de habilita\u00e7\u00e3o na <strong>categoria \u201cB\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 em rela\u00e7\u00e3o a remunera\u00e7\u00e3o inicial para Investigador,  os sal\u00e1rios chegam a <strong>R$ 5.840,37.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2022\/01\/Faixa-Frete-Gr%E2%80%A0tis-portal.png\" alt=\"assinatura completa\" class=\"wp-image-153078\" loading=\"lazy\" title=\"\"><\/a><figcaption><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Aten\u00e7\u00e3o concurseiros! As\u00a0provas\u00a0do\u00a0Concurso PC RJ\u00a0(Pol\u00edcia Civil do Rio de Janeiro), para Investigador ser\u00e3o aplicadas no pr\u00f3ximo domingo,\u00a013 de fevereiro.\u00a0Confira os locais de prova!\u00a0S\u00e3o 200 vagas! Confira:\u00a0Curso Gr\u00e1tis Pol\u00edcia Civil RJ (Gr\u00e1tis) Estude para o concurso dos seus sonhos com a\u00a0Assinatura Completa da Nova. Tenha acesso a Cursos, Plataforma de Quest\u00f5es, Eventos Exclusivos para Assinantes e [&hellip;]<\/p>\n","protected":false},"author":54671,"featured_media":149510,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-155240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/155240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54671"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=155240"}],"version-history":[{"count":6,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/155240\/revisions"}],"predecessor-version":[{"id":155307,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/155240\/revisions\/155307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/149510"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=155240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=155240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=155240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}