{"id":156436,"date":"2022-02-24T09:33:44","date_gmt":"2022-02-24T12:33:44","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=156436"},"modified":"2022-02-25T09:48:43","modified_gmt":"2022-02-25T12:48:43","slug":"concurso-stj-edital-dezembro-confira-detalhes","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-stj-edital-dezembro-confira-detalhes\/","title":{"rendered":"Concurso STJ: Edital at\u00e9 dezembro. Confira mais detalhes!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aten\u00e7\u00e3o concurseiros! O <strong>edital <\/strong>do <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-stj\/\">concurso STJ<\/a> (Superior Tribunal de Justi\u00e7a) deve ser publicado at\u00e9 o <strong>m\u00eas de dezembro, <\/strong>com os tr\u00e2mites tendo in\u00edcio j\u00e1 em fevereiro! O concurso inclusive <strong>est\u00e1 no Or\u00e7amento<\/strong> deste ano!<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Confira:<\/strong> <a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/porcentagens-para-concursos\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Guia Porcentagem para Concursos (Gr\u00e1tis) (abre numa nova aba)\">Guia Porcentagem para Concursos (Gr\u00e1tis)<\/a><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estude para o concurso dos seus sonhos com a\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Assinatura Completa da Nova<\/a>\u00a0. Tenha acesso a Cursos, Plataforma de Quest\u00f5es, Eventos Exclusivos para Assinantes e Muito Mais!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-stj-quando-sai-o-edital\">Concurso STJ: quando sai o edital?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 o que os concurseiros interessados querem saber! E, com a comiss\u00e3o formada, \u00e9 poss\u00edvel que o <strong>edital saia no segundo semestre deste ano.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o<strong> Superior Tribunal de Justi\u00e7a<\/strong>, o documento poder\u00e1 ser publicado at\u00e9 o m\u00eas de dezembro, entretanto, poder\u00e1 sair at\u00e9 antes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o \u00f3rg\u00e3o, a <strong>comiss\u00e3o formada j\u00e1 vai dar in\u00edcio aos trabalhos <\/strong>neste m\u00eas de fevereiro, realizando estudos e fazendo o levantamento de cargos e vagas!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O \u00f3rg\u00e3o ainda informou que o prazo para <strong>contratar a banca organizadora \u00e9<\/strong> no segundo semestre, mas, n\u00e3o deu uma data espec\u00edfica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, tudo depender\u00e1 de quando o processo licitat\u00f3rio ser\u00e1 iniciado. Ademais, isso depende ainda da <strong>conclus\u00e3o dos estudos que ser\u00e3o feitos <\/strong>pela comiss\u00e3o. Portanto, tudo com calma e devagar!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o STJ afirma que o <strong>edital deve ser lan\u00e7ado em at\u00e9 tr\u00eas meses <\/strong>ap\u00f3s a contrata\u00e7\u00e3o da banca. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deste modo, a <strong>banca precisa ser definida e oficializada<\/strong> at\u00e9 setembro para que o edital possa sair at\u00e9 dezembro, como o esperado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, o Superior Tribunal de Justi\u00e7a garantiu que o <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-previstos\/nacional\">concurso <\/a>vigente, realizado em 2018, n\u00e3o ser\u00e1\u00a0<strong>\u201cimpactado pela cria\u00e7\u00e3o e funcionamento da referida comiss\u00e3o.\u201d<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Comiss\u00e3o formada<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A <strong>comiss\u00e3o <\/strong>organizadora do concurso foi <strong>formada <\/strong>de acordo com a portaria\u00a0STJ\/GP n\u00ba 48 do dia<strong> 16 de fevereiro<\/strong>, publicada no\u00a0Di\u00e1rio Oficial Eletr\u00f4nico do pr\u00f3prio \u00f3rg\u00e3o. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o <strong>grupo ser\u00e1 respons\u00e1vel <\/strong>pelo levantamento\/estudo sobre os cargos vagos, al\u00e9m do processo de escolha da banca. Portanto, confira os servidores:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Dalila Ta\u00eds Miguel de Souza;<\/li><li>Larissa Ara\u00fajo Amaro;<\/li><li>Mariza Gontijo Esteves Gerardo da Silva Gomes; e<\/li><li>Anderson Luiz de Fran\u00e7a Silva.<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o \u00f3rg\u00e3o tem expectativa de que o<strong>\u00a0concurso contemple cargos de n\u00edveis m\u00e9dio e superior da \u00e1rea de apoio do STJ<\/strong>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"oramento-federal-traz-o-concurso-stj\"><strong>Or\u00e7amento Federal traz o concurso STJ<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Um outro ind\u00edcio de que o <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/nacional\">concurso <\/a>ser\u00e1 publicado neste ano \u00e9 que ele aparece na autoriza\u00e7\u00e3o do <strong>Or\u00e7amento 2022, sancionado pelo presidente <\/strong>da Rep\u00fablica, Jair Messias Bolsonaro.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, esse quantitativo pode ser utilizado para chamada de aprovados do <strong>concurso de 2018 e tamb\u00e9m para um novo edital. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, no total h\u00e1 <strong>57 provimentos previstos no \u00f3rg\u00e3o<\/strong>, o que deve fazer com que o edital seja em torno disso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cH\u00e1 a necessidade de recomposi\u00e7\u00e3o da for\u00e7a de trabalho pelo represamento da realiza\u00e7\u00e3o dos concursos nos \u00faltimos tr\u00eas anos\u201d<\/em>, disse o secret\u00e1rio de or\u00e7amento, Ariosto Culau.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2022\/01\/Faixa-Frete-Gr%E2%80%A0tis-portal.png\" alt=\"assinatura completa\" class=\"wp-image-153078\" loading=\"lazy\" title=\"\"><\/a><figcaption><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Aten\u00e7\u00e3o concurseiros! O edital do concurso STJ (Superior Tribunal de Justi\u00e7a) deve ser publicado at\u00e9 o m\u00eas de dezembro, com os tr\u00e2mites tendo in\u00edcio j\u00e1 em fevereiro! O concurso inclusive est\u00e1 no Or\u00e7amento deste ano! Confira: Guia Porcentagem para Concursos (Gr\u00e1tis) Estude para o concurso dos seus sonhos com a\u00a0Assinatura Completa da Nova\u00a0. Tenha acesso [&hellip;]<\/p>\n","protected":false},"author":54671,"featured_media":156440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-156436","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/156436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54671"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=156436"}],"version-history":[{"count":5,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/156436\/revisions"}],"predecessor-version":[{"id":156520,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/156436\/revisions\/156520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/156440"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=156436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=156436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=156436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}