{"id":157105,"date":"2022-03-08T09:56:49","date_gmt":"2022-03-08T12:56:49","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=157105"},"modified":"2022-03-08T09:56:55","modified_gmt":"2022-03-08T12:56:55","slug":"concurso-inss-servidores-paralisacao-reivindicando-edital","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-inss-servidores-paralisacao-reivindicando-edital\/","title":{"rendered":"Concurso INSS: Servidores promovem paralisa\u00e7\u00e3o reivindicando novo edital. Veja detalhes!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Servidores do Instituto Nacional de Seguro Social <strong>realizar\u00e3o uma paralisa\u00e7\u00e3o<\/strong> nesta quarta-feira (9),<strong> reivindicando um novo edital <\/strong>para o <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-inss\/\">concurso INSS<\/a>. Confira os itens que ser\u00e3o pauta de reuni\u00e3o!<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Confira:\u00a0<\/strong><a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/www.novaconcursos.com.br\/eventos\/guia-definitivo-plano-de-estudos-passo-a-passo\/\" target=\"_blank\">Guia Definitivo Plano de Estudos \u2013 Gr\u00e1tis<\/a><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estude para o concurso dos seus sonhos com a\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Assinatura Completa da Nova<\/a>. Tenha acesso a Cursos, Plataforma de Quest\u00f5es, Eventos Exclusivos para Assinantes e Muito Mais!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-inss-paralizao-acontece-nesta-quartafeira\">Concurso INSS: paraliza\u00e7\u00e3o acontece nesta quarta-feira<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1 marcada para esta quarta-feira, 9 de mar\u00e7o, uma <strong>paralisa\u00e7\u00e3o dos servidores <\/strong>do Instituto Nacional de Seguro Social.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Adquira<\/strong>:\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/inss-instituto-nacional-do-seguro-social\/apostila\">Apostila Concurso INSS<\/a><\/li><li><strong>Adquira<\/strong>:\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/curso-online\/pacote-completo-inss-tecnico-seguro-social\">Curso Online INSS<\/a><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, eles pedem um novo <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-previstos\/nacional\">concurso p\u00fablico<\/a> para o instituto, uma vez que os cargos vagos t\u00eam aumentado e<strong> h\u00e1 falta de servidores.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, a participa\u00e7\u00e3o de trabalhadores(as) <strong>ser\u00e1 representada por 12 Estados e o Distrito Federal.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, ela <strong>foi autorizada pela Plen\u00e1ria<\/strong> Nacional da Fenasps. Ser\u00e3o 24h de paralisa\u00e7\u00e3o e realiza\u00e7\u00e3o de atos nesta quarta-feira. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso porque a Plen\u00e1ria aprovou ainda a intensifica\u00e7\u00e3o da mobiliza\u00e7\u00e3o para deflagra\u00e7\u00e3o da <strong>GREVE GERAL dos Servidores P\u00fablicos Federais<\/strong> a partir de 23 de mar\u00e7o. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cOrientamos todos(as) os(as) servidores(as) para se organizarem e aderirem \u00e0 Greve\u201d<\/em>, pediu a <strong>Federa\u00e7\u00e3o <\/strong>Nacional dos Sindicatos de Trabalhadores em Sa\u00fade, Trabalho, Previd\u00eancia e Assist\u00eancia Social. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pontos principais<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, confira um resumo com as<strong> principais resolu\u00e7\u00f5es <\/strong>aprovadas na Plen\u00e1ria Nacional do \u00faltimo s\u00e1bado, 5 de mar\u00e7o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Orientar que os Servidores realizem paralisa\u00e7\u00e3o das atividades com atos nos locais de trabalho. Orientar os servidores a realizar paralisa\u00e7\u00e3o e atos nos locais de trabalho no dia 9 de mar\u00e7o (data que ter\u00e1 reuni\u00e3o com o ministro do Trabalho e Previd\u00eancia, Onyx Lorenzoni). Que os servidores no teletrabalho n\u00e3o puxem tarefas, com apag\u00e3o total das atividades do INSS.<\/li><li>Orientar os Estados a enviarem caravanas a Bras\u00edlia dia 16 de Mar\u00e7o para ato por reajuste salarial emergencial;<\/li><li>Indicativo de Greve Geral Unificada com Servidores P\u00fablicos Federais a partir de 23 de mar\u00e7o. Reivindica\u00e7\u00f5es: reposi\u00e7\u00e3o salarial de 19,99%, melhores Condi\u00e7\u00f5es de Trabalho, Plano de Carreira e em Defesa do Servi\u00e7o P\u00fablico;<\/li><li>Orientar os Estados filiados e oposi\u00e7\u00f5es quanto \u00e0 instala\u00e7\u00e3o do Comando de Mobiliza\u00e7\u00e3o para construir a GREVE.<\/li><li>Ap\u00f3s DEFLAGRA\u00c7\u00c3O DA GREVE, instala\u00e7\u00e3o do Comando Nacional de Greve.<\/li><li>Quem entrar em Greve, orienta-se que informe aos Sindicatos ou Comando de Greve do Respectivo Estado onde trabalha.<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"https:\/\/fenasps.org.br\/wp-content\/uploads\/2022\/03\/rela.plena_.nac_05.03.22.pdf\" target=\"_blank\"><strong>Confira aqui<\/strong><\/a>\u00a0a \u00edntegra das resolu\u00e7\u00f5es aprovadas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reuni\u00e3o em pauta<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, no mesmo dia, haver\u00e1 uma <strong>reuni\u00e3o do ministro do Trabalho e Previd\u00eancia Social, Onyx Lorenzoni,<\/strong> com representantes sindicais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, confira abaixo <strong>alguns dos itens<\/strong> que ser\u00e3o pauta da reuni\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Novo edital para o INSS<\/li><li>Implementa\u00e7\u00e3o do Programa de Gest\u00e3o<\/li><li>redu\u00e7\u00e3o de 20% em rela\u00e7\u00e3o \u00e0s metas exigidas<\/li><li>cria\u00e7\u00e3o do Aux\u00edlio Teletrabalho, o aux\u00edlio sa\u00fade e creche, vale-alimenta\u00e7\u00e3o<\/li><li>derrubada do veto de R$ 1 bilh\u00e3o no or\u00e7amento do INSS<\/li><li>reposi\u00e7\u00e3o salarial de 19,99%<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quando-sai-o-novo-edital-do-concurso-inss\">Quando sai o novo edital do concurso INSS?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 o que os concurseiros e servidores buscam saber! E segundo informa\u00e7\u00f5es, a autoriza\u00e7\u00e3o para o <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/nacional\">novo certame<\/a> <strong>deve sair ainda neste m\u00eas de mar\u00e7o.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o presidente do Instituto Nacional de Seguro Social (INSS) Leonardo Rolim, j\u00e1 informou que a<strong> inten\u00e7\u00e3o \u00e9 realizar o concurso<\/strong> antes das elei\u00e7\u00f5es presidenciais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo ele, isso seria para que as <strong>nomea\u00e7\u00f5es ocorram ainda em 2022. <\/strong>Entretanto, para isso o Ministro da Economia, Paulo Guedes, deve autorizar o edital at\u00e9 abril!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Mais de 7 mil vagas solicitadas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Moarcir Lopes,\u00a0presidente da Fenasps, disse ainda em 2021 que<strong> 7.500 vagas foram solicitadas <\/strong>e devem ser autorizadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> <em>\u201cNa audi\u00eancia com o presidente do INSS, nos dias 8 e 13 de setembro, o mesmo reafirmou que existe a verba no or\u00e7amento para realizar concurso para 7.500 vagas. Vamos agora pressionar o governo para a realiza\u00e7\u00e3o do concurso\u201d,<\/em> afirmou Moarcir Lopes,\u00a0presidente da Fenasps, ainda em 2021. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, somente para <strong>repor o quadro de tempor\u00e1rios <\/strong>o INSS precisa de mais de 3 mil vagas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o pedido de concurso INSS foi enviado e<strong> segue em an\u00e1lise no Minist\u00e9rio da Economia;<\/strong>\u00a0s\u00e3o vagas\u00a0em todo o pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2022\/01\/Faixa-Frete-Gr%E2%80%A0tis-portal.png\" alt=\"assinatura completa\" class=\"wp-image-153078\" loading=\"lazy\" title=\"\"><\/a><figcaption><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Servidores do Instituto Nacional de Seguro Social realizar\u00e3o uma paralisa\u00e7\u00e3o nesta quarta-feira (9), reivindicando um novo edital para o concurso INSS. Confira os itens que ser\u00e3o pauta de reuni\u00e3o! Confira:\u00a0Guia Definitivo Plano de Estudos \u2013 Gr\u00e1tis Estude para o concurso dos seus sonhos com a\u00a0Assinatura Completa da Nova. Tenha acesso a Cursos, Plataforma de Quest\u00f5es, [&hellip;]<\/p>\n","protected":false},"author":54671,"featured_media":155656,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-157105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/157105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54671"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=157105"}],"version-history":[{"count":4,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/157105\/revisions"}],"predecessor-version":[{"id":157109,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/157105\/revisions\/157109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/155656"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=157105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=157105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=157105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}