{"id":161860,"date":"2022-05-26T10:45:13","date_gmt":"2022-05-26T13:45:13","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=161860"},"modified":"2024-07-04T15:43:42","modified_gmt":"2024-07-04T18:43:42","slug":"concurso-pf-e-prf-publicada-a-autorizacao-para-convocacao-de-excedentes","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-pf-e-prf-publicada-a-autorizacao-para-convocacao-de-excedentes\/","title":{"rendered":"Concurso PF e PRF: Publicada a autoriza\u00e7\u00e3o para convoca\u00e7\u00e3o de excedentes!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aten\u00e7\u00e3o concurseiros! O presidente Jair Bolsonaro j\u00e1 havia anunciado\u00a0<strong>625 convoca\u00e7\u00f5es de excedentes<\/strong>\u00a0para o\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-policia-federal\/\">Concurso PF<\/a>\u00a0e\u00a0<strong>625\u00a0<\/strong>para o\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-prf\/\">Concurso PRF<\/a>. Assim, agora foi \u00b4publicada a autoriza\u00e7\u00e3o para convoca\u00e7\u00e3o! Veja!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estude para o concurso dos seus sonhos com a\u00a0<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\">Assinatura Completa da Nova<\/a>. Tenha acesso a Cursos, Plataforma de Quest\u00f5es, Eventos Exclusivos para Assinantes e Muito Mais!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concursos-pf-e-prf-quando-sairo-as-convocaes\">Concursos PF e PRF: quando sair\u00e3o as convoca\u00e7\u00f5es?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Recentemente, o Presidente da Rep\u00fablica, Jair Bolsonaro, j\u00e1 havia <strong>confirmado <\/strong>sobre mais\u00a0<strong>convoca\u00e7\u00f5es\u00a0<\/strong>para a Pol\u00edcia Federal e Pol\u00edcia Rodovi\u00e1ria Federal.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Adquira<\/strong>:\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pf-policia-federal\/apostila\">Apostila Concurso PF<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pf-policia-federal\/curso-online\">Curso Online PF<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/prf-policia-rodoviaria-federal\/apostila\">Apostila Concurso PRF<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/prf-policia-rodoviaria-federal\/curso-online\">Curso Online PRF<\/a><\/li>\n<\/ul><\/li>\n<\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agora, o <strong>decreto que autoriza a chamada<\/strong> de mais aprovados foi publicado no Di\u00e1rio Oficial da Uni\u00e3o desta quinta-feira (26).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, <strong>est\u00e3o autorizadas oficialmente<\/strong> a nomea\u00e7\u00e3o de mais 1.250 candidatos que participara das sele\u00e7\u00f5es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cAcabei de assinar dois decretos que autorizam ent\u00e3o, por parte da PF e da PRF, iniciar o curso de forma\u00e7\u00e3o para 625 policiais federais e 625 policiais rodovi\u00e1rios federais. Eu sempre digo que o trabalho deles \u00e9 excepcional para o Brasil e merecem o reconhecimento por tudo isso, no combate ao crime, aos il\u00edcitos, no combate de tr\u00e1fico de drogas, de apreens\u00e3o<\/em>\u201c, disse o presidente na quarta-feira! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Ent\u00e3o um trabalho fant\u00e1stico. Eles s\u00e3o lucrativos para o Brasil. O reconhecimento \u00e9 importante e a gente espera no momento certo poder garantir materialmente at\u00e9 o reconhecimento aos policiais federais e rodovi\u00e1rios federais\u201d<\/em>, completou Bolsonaro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, o presidente <strong>n\u00e3o deu mais detalhes<\/strong> de quando acontecer\u00e3o as convoca\u00e7\u00f5es, mas \u00e9 poss\u00edvel que sejam em breve!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concursos-pf-e-prf-editais-ofertaram-um-total-de-3-mil-vagas\"><strong>Concursos PF e PRF: editais ofertaram um total de 3 mil vagas<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vale destacar que, juntos, os editais dos\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/nacional\">concursos<\/a> da Pol\u00edcia Federal e Pol\u00edcia Rodovi\u00e1ria Federal\u00a0<strong>ofertaram um total de 3 mil vagas.<\/strong> Assim, foram <strong>1.500 para cada corpora\u00e7\u00e3o<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, na PRF, o cargo ofertado \u00e9 de\u00a0<strong>Policial Rodovi\u00e1rio Federal<\/strong>, que tem exig\u00eancia de n\u00edvel superior em qualquer \u00e1rea. Entretanto, \u00e9 preciso ainda CNH, no m\u00ednimo, na categoria B.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enquanto isso, na PF, as vagas s\u00e3o para o<strong>\u00a0n\u00edvel superior.<\/strong>\u00a0Assim, com jornada de 40 horas semanais, confira a divis\u00e3o de cargos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Agente de pol\u00edcia<\/strong>\u00a0\u00a0\u2013 893 vagas<\/li>\n\n\n\n<li><strong>Escriv\u00e3o de pol\u00edcia\u00a0<\/strong>\u00a0\u2013 400 vagas;<\/li>\n\n\n\n<li><strong>Papiloscopista policial federal\u00a0<\/strong>\u00a0\u2013 84 vagas;<\/li>\n\n\n\n<li><strong>Delegado de pol\u00edcia<\/strong>\u00a0\u00a0\u2013 123 vagas.<\/li>\n<\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"novos-editais-sero-publicados-quando-para-que-reas\">Novos editais ser\u00e3o publicados? Quando? Para que \u00e1reas?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 poss\u00edvel que <strong>mais editais cheguem para as corpora\u00e7\u00f5es para 2022<\/strong>. Pelo menos que o que sinalizam os respons\u00e1veis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso porque um <strong>novo pedido<\/strong>\u00a0foi encaminhado para o Minist\u00e9rio da Economia, solicitando um novo concurso para\u00a0<strong>5 mil vagas<\/strong>\u00a0na Pol\u00edcia Rodovi\u00e1ria Federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, no documento, o diretor-geral explicou que o motivo se deve ao projeto de\u00a0<strong>reestrutura\u00e7\u00e3o do \u00f3rg\u00e3o<\/strong>\u00a0que est\u00e1 em tramita\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, na reorganiza\u00e7\u00e3o est\u00e1\u00a0<strong>prevista a majora\u00e7\u00e3o<\/strong>\u00a0do quadro legal de pessoal da PRF, possibilitando assim a demanda por amplia\u00e7\u00e3o do efetivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o pedido apresenta ainda um poss\u00edvel\u00a0<strong>cronograma de etapas e convoca\u00e7\u00f5es\u00a0<\/strong>do certame.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 na Pol\u00edcia Federal, um projeto articula a\u00a0<strong>cria\u00e7\u00e3o de 2.967 vagas<\/strong>\u00a0para o fortalecimento da capacidade institucional e opera\u00e7\u00e3o do \u00f3rg\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o pedido ainda aponta unidades do \u00f3rg\u00e3o que operam com efetivo abaixo do m\u00ednimo necess\u00e1rio. Atualmente\u00a0<strong>s\u00e3o 450 cargos vagos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2022\/01\/Faixa-Frete-Gr%E2%80%A0tis-portal.png\" alt=\"assinatura completa\" class=\"wp-image-153078\" loading=\"lazy\" title=\"\"><\/a><figcaption><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Aten\u00e7\u00e3o concurseiros! O presidente Jair Bolsonaro j\u00e1 havia anunciado\u00a0625 convoca\u00e7\u00f5es de excedentes\u00a0para o\u00a0Concurso PF\u00a0e\u00a0625\u00a0para o\u00a0Concurso PRF. Assim, agora foi \u00b4publicada a autoriza\u00e7\u00e3o para convoca\u00e7\u00e3o! Veja! Estude para o concurso dos seus sonhos com a\u00a0Assinatura Completa da Nova. Tenha acesso a Cursos, Plataforma de Quest\u00f5es, Eventos Exclusivos para Assinantes e Muito Mais! Concursos PF e PRF: [&hellip;]<\/p>\n","protected":false},"author":54671,"featured_media":159345,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-161860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/161860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54671"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=161860"}],"version-history":[{"count":5,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/161860\/revisions"}],"predecessor-version":[{"id":242725,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/161860\/revisions\/242725"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/159345"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=161860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=161860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=161860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}