{"id":163240,"date":"2022-06-20T10:32:00","date_gmt":"2022-06-20T13:32:00","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=163240"},"modified":"2022-06-21T09:07:56","modified_gmt":"2022-06-21T12:07:56","slug":"concurso-pc-go-aocp-e-a-banca-para-nivel-superior","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-pc-go-aocp-e-a-banca-para-nivel-superior\/","title":{"rendered":"Concurso PC GO: Instituto AOCP \u00e9 a banca. 864 vagas!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aten\u00e7\u00e3o concurseiros! A <strong>banca <\/strong>organizadora do novo\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-pc-go\/\">concurso PC GO<\/a> foi anunciada e ser\u00e1 o <strong>Instituto AOCP<\/strong>. Portanto, o edital deve sair a qualquer momento. Ademais, vale recordar que ser\u00e3o ofertadas<strong> 864 vagas de n\u00edvel superior<\/strong>. Veja detalhes!<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Confira:\u00a0<\/strong><a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pc-go-policia-civil-de-goias\/apostila\">Apostila Concurso PC GO<\/a><\/li><li><strong>Confira:<\/strong>\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pc-go-policia-civil-de-goias\/curso-online\">Curso Online Concurso PC GO<\/a><\/li><\/ul><h2 class=\"wp-block-heading\" id=\"concurso-pc-go-banca-confirmada-e-o-edital\">Concurso PC GO: banca confirmada; e o edital?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, uma publica\u00e7\u00e3o no Di\u00e1rio Oficial do estado desta segunda-feira (20), confirmou o <strong>Instituto AOCP como banca <\/strong>organizadora\u00a0do pr\u00f3ximo concurso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, com a banca confirmada, o <strong>edital deve ser publicado<\/strong> muito em breve. Vale destacar que a previs\u00e3o era de que ele sairia dia 13 de maio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, est\u00e3o previstas\u00a0<strong>864 oportunidades<\/strong>\u00a0entre carreiras de\u00a0<strong>n\u00edvel superior.<\/strong> Portanto, confira a distribui\u00e7\u00e3o das vagas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Escriv\u00e3o \u2013 200 vagas;<\/li><li>Agente \u2013 560 vagas;<\/li><li>Papiloscopista \u2013 60 vagas;<\/li><li>Delegado \u2013 44 vagas.<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, os aprovados no concurso p\u00fablico poder\u00e3o contar com\u00a0<strong>sal\u00e1rios iniciais<\/strong>\u00a0nos valores de\u00a0<strong>R$ 6.358,00<\/strong>\u00a0para Agente, Escriv\u00e3o e Papiloscopista e de\u00a0<strong>R$ 21.615,00<\/strong>\u00a0para Delegado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, para concorrer a um dos cargos \u00e9 necess\u00e1rio possuir\u00a0<strong>idade m\u00ednima de 18 anos,\u00a0<\/strong>de forma que\u00a0<strong>n\u00e3o h\u00e1 idade m\u00e1xima<\/strong>\u00a0para concorrer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, os interessados no cargo de<strong>\u00a0Agente<\/strong>\u00a0tamb\u00e9m precisam ter a\u00a0<strong>Carteira Nacional de Habilita\u00e7\u00e3o<\/strong>\u00a0(CNH) na categoria \u201cB\u201d, no m\u00ednimo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-pc-go-convocaes\"><strong>Concurso PC GO: convoca\u00e7\u00f5es<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Vale destacar que o que se espera \u00e9 que as\u00a0<strong>convoca\u00e7\u00f5es dos aprovados<\/strong>\u00a0no concurso da Pol\u00edcia Civil de\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-previstos\/go\/\">Goi\u00e1s<\/a>\u00a0aconte\u00e7am\u00a0<strong>entre 2022 e 2023,\u00a0<\/strong>da seguinte maneira:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Convoca\u00e7\u00f5es para 2022:<\/strong><ul><li>Escriv\u00e3o de Pol\u00edcia: 100 convoca\u00e7\u00f5es<\/li><li>Agente de Pol\u00edcia: 350 convoca\u00e7\u00f5es<\/li><li>Papiloscopista: 20 convoca\u00e7\u00f5es<\/li><\/ul><\/li><li><strong>Convoca\u00e7\u00f5es para 2023:<\/strong><ul><li>Delegado de Pol\u00edcia Substituto: 44 convoca\u00e7\u00f5es<\/li><li>Escriv\u00e3o de Pol\u00edcia: 100 convoca\u00e7\u00f5es<\/li><li>Agente de Pol\u00edcia: 210 convoca\u00e7\u00f5es<\/li><li>Papiloscopista: 40 convoca\u00e7\u00f5es<\/li><\/ul><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quais-sero-as-etapas-de-avaliao-do-concurso-pc-go\"><strong>Quais ser\u00e3o as etapas de avalia\u00e7\u00e3o do concurso PC GO?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, \u00e9 essencial que os concurseiros saibam que podem tomar como base o\u00a0<strong>\u00faltimo edital<\/strong>\u00a0para a Pol\u00edcia Civil de <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/go\/\">Goi\u00e1s<\/a>,\u00a0<strong>de 2016, para iniciar os estudos. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale destacar que na \u00faltima sele\u00e7\u00e3o os inscritos foram avaliados por meio de <strong>v\u00e1rias etapas<\/strong>. Portanto, veja quais:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Provas objetivas<\/li><li>Prova discursiva<\/li><li>Avalia\u00e7\u00e3o m\u00e9dica<\/li><li>Avalia\u00e7\u00e3o de aptid\u00e3o f\u00edsica<\/li><li>Exame psicot\u00e9cnico<\/li><li>Prova pr\u00e1tica de digita\u00e7\u00e3o (somente para Escriv\u00e3o)<\/li><li>Avalia\u00e7\u00e3o de vida pregressa e investiga\u00e7\u00e3o social<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesse sentido, na\u00a0<strong>prova objetiva<\/strong> os candidatos responderam a\u00a0<strong>70 quest\u00f5es<\/strong> de m\u00faltipla escolha acerca dos conte\u00fados de Conhecimentos <strong>B\u00e1sicos,<\/strong> <strong>Gerais<\/strong> e <strong>Espec\u00edficos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, as\u00a0<strong>disciplinas em comum<\/strong>\u00a0cobradas para todos os cargos foram as seguintes:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>L\u00edngua Portuguesa<\/li><li>Inform\u00e1tica<\/li><li>Legisla\u00e7\u00e3o Penal Extravagante<\/li><li>Legisla\u00e7\u00e3o Espec\u00edfica<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, os conte\u00fados de\u00a0<strong>Conhecimentos Espec\u00edficos<\/strong>\u00a0para os cargos de\u00a0<strong>Agente e Escriv\u00e3o<\/strong>\u00a0foram os indicados a seguir:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Direito:<ul><li>Constitucional<\/li><li>Administrativo<\/li><li>Penal<\/li><li>Processual Penal<\/li><\/ul><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 igualmente essencial destacar que para a\u00a0<strong>prova discursiva<\/strong>\u00a0os candidatos elaboraram um<strong>\u00a0texto dissertativo<\/strong>\u00a0que deveria possuir, no m\u00e1ximo,\u00a0<strong>30 linhas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2022\/01\/Faixa-Frete-Gr%E2%80%A0tis-portal.png\" alt=\"assinatura completa\" class=\"wp-image-153078\" loading=\"lazy\" title=\"\"><\/a><figcaption><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Aten\u00e7\u00e3o concurseiros! A banca organizadora do novo\u00a0concurso PC GO foi anunciada e ser\u00e1 o Instituto AOCP. Portanto, o edital deve sair a qualquer momento. Ademais, vale recordar que ser\u00e3o ofertadas 864 vagas de n\u00edvel superior. Veja detalhes! Confira:\u00a0Apostila Concurso PC GO Confira:\u00a0Curso Online Concurso PC GO Concurso PC GO: banca confirmada; e o edital? Assim, [&hellip;]<\/p>\n","protected":false},"author":54671,"featured_media":155812,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-163240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/163240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54671"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=163240"}],"version-history":[{"count":7,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/163240\/revisions"}],"predecessor-version":[{"id":163326,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/163240\/revisions\/163326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/155812"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=163240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=163240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=163240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}