{"id":163471,"date":"2022-06-22T12:01:24","date_gmt":"2022-06-22T15:01:24","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=163471"},"modified":"2022-06-22T16:22:02","modified_gmt":"2022-06-22T19:22:02","slug":"concurso-pf-comissao-aprova-orcamento-para-convocacao","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-pf-comissao-aprova-orcamento-para-convocacao\/","title":{"rendered":"Concurso PF: Comiss\u00e3o aprova or\u00e7amento para convoca\u00e7\u00e3o de todos os excedentes!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aten\u00e7\u00e3o concurseiros! Publicada a\u00a0<strong>convoca\u00e7\u00e3o<\/strong>\u00a0de mais excedentes para a realiza\u00e7\u00e3o da\u00a0<strong>matr\u00edcula\u00a0<\/strong>na segunda turma do Curso de Forma\u00e7\u00e3o Profissional no\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-policia-federal\/\">concurso PF<\/a>, o <strong>or\u00e7amento agora foi aprovado<\/strong>, veja!<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Confira:<\/strong>\u00a0<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/www.novaconcursos.com.br\/eventos\/guia-definitivo-como-montar-um-mapa-mental\/\" target=\"_blank\">Guia como montar um mapa mental (Gr\u00e1tis)<\/a><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estude para o concurso dos seus sonhos com a\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\">Assinatura Completa da Nova<\/a>. Tenha acesso a Cursos, Plataforma de Quest\u00f5es, Eventos Exclusivos para Assinantes e Muito Mais!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-pf-oramento-aprovado-e-convocaes-em-breve\">Concurso PF: or\u00e7amento aprovado e convoca\u00e7\u00f5es em breve!<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Recentemente, o Presidente Jair Bolsonaro j\u00e1 havia\u00a0<strong>confirmado\u00a0<\/strong>sobre mais <strong>convoca\u00e7\u00f5es\u00a0<\/strong>para a Pol\u00edcia Federal.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Adquira:<\/strong>\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pf-policia-federal\/apostila\">Apostila Concurso PF<\/a><\/li><li><strong>Adquira:<\/strong>\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/concurso\/pf-policia-federal\/curso-online\">Curso Online PF<\/a><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E os aprovados no \u00faltimo concurso, <strong>realizado em 2021<\/strong>, tiveram uma \u00f3tima not\u00edcia nesta ter\u00e7a-feira (21).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso porque foi aprovada pela Comiss\u00e3o de Seguran\u00e7a P\u00fablica e Combate ao Crime Organizado, a emenda de\u00a0<strong>previs\u00e3o or\u00e7ament\u00e1ria<\/strong>\u00a0para a\u00a0<strong>LDO 2023<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sendo assim, a medida torna poss\u00edvel a convoca\u00e7\u00e3o de\u00a0<strong>todos os excedentes<\/strong> aprovados na sele\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, agora a emenda <strong>ser\u00e1 encaminhada<\/strong> \u00e0 Comiss\u00e3o Mista de Or\u00e7amento para, posteriormente ser inclu\u00edda na LDO e, por fim, se aprovada, integrar a LOA. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale destacar que recentemente o\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.cebraspe.org.br\/concursos\/pf_21\" target=\"_blank\">Cebraspe<\/a>, banca organizadora,\u00a0<strong>publicou a convoca\u00e7\u00e3o<\/strong>\u00a0de mais aprovados no\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-previstos\/nacional\">concurso<\/a>\u00a0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, importante destacar que a\u00a0<strong>convoca\u00e7\u00e3o<\/strong>\u00a0dos excedentes para a realiza\u00e7\u00e3o da matr\u00edcula na segunda turma do Curso de Forma\u00e7\u00e3o Profissional \u00e9 apenas para o cargo de<strong>\u00a0Escriv\u00e3o.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Confira o documento,\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/cdn.cebraspe.org.br\/concursos\/pf_21\/arquivos\/ED_65_PF_21_CONV_CAND_EXCEDENTES.PDF\" target=\"_blank\">clicando aqui<\/a>!<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale destacar que a sele\u00e7\u00e3o registrou\u00a0<strong>53.486 inscritos para o cargo\u00a0<\/strong>de Escriv\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, a nota de corte da prova para o cargo foi de\u00a0<strong>66 pontos<\/strong>\u00a0para a ampla concorr\u00eancia e\u00a0<strong>59 para cotas raciais.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Convoca\u00e7\u00e3o de Agentes e Delegados<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, recentemente tamb\u00e9m foram convocados os aprovados nos cargos de\u00a0<strong>Agente e Delegado.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, o per\u00edodo de <strong>matr\u00edcula j\u00e1 foi encerrado<\/strong> ainda neste m\u00eas de junho. Sendo assim,\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/pesquisa.in.gov.br\/imprensa\/jsp\/visualiza\/index.jsp?data=17\/05\/2022&amp;jornal=530&amp;pagina=156&amp;totalArquivos=380\" target=\"_blank\">clique e confira<\/a>!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cEsse grande refor\u00e7o demonstra nosso compromisso com a seguran\u00e7a p\u00fablica do Brasil e as nossas pol\u00edcias. A previs\u00e3o \u00e9 que, em junho, os policiais comecem a se apresentar. Em outubro, j\u00e1 teremos 625 PRFs trabalhando em todo o Brasil. Os federais ainda passam por curso de forma\u00e7\u00e3o, mas at\u00e9 dezembro est\u00e3o todos na ativa. Ser\u00e3o mais 1.250 policiais na ativa\u201d,<\/em>\u00a0comemorou o ministro da Justi\u00e7a, Anderson Torres.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quando ocorrer\u00e1 o CFP?<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme o cronograma, o CFP foram confirmados para acontecer d<strong>e junho a setembro<\/strong>. Portanto, ser\u00e1 de 13\/06 a 02\/09.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poder\u00e3o ser desenvolvidas atividades, a\u00a0<strong>crit\u00e9rio da Administra\u00e7\u00e3o<\/strong>, em qualquer Unidade da Federa\u00e7\u00e3o<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O CFP ocorrer\u00e1 no per\u00edodo das\u00a0<strong>7 horas e 30 minutos\u00a0<\/strong>de segunda-feira \u00e0s\u00a0<strong>18 horas<\/strong>\u00a0de s\u00e1bado (hor\u00e1rio oficial de Bras\u00edlia\/DF).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante o curso, o\u00a0<strong>aluno regularmente matriculado\u00a0<\/strong>far\u00e1 jus a aux\u00edlio-financeiro, na forma da legisla\u00e7\u00e3o vigente, no valor de 50% do subs\u00eddio da classe inicial do cargo.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Saiba mais detalhes no\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/cdn.cebraspe.org.br\/concursos\/pf_21\/arquivos\/ED_65_PF_21_CONV_CAND_EXCEDENTES.PDF\" target=\"_blank\">final deste documento<\/a>!<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Publicado em janeiro de 2021, o\u00a0<strong>concurso PF tem oferta de 1.500 vagas<\/strong>\u00a0imediatas e efetivas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2022\/01\/Faixa-Frete-Gr%E2%80%A0tis-portal.png\" alt=\"assinatura completa\" class=\"wp-image-153078\" loading=\"lazy\" title=\"\"><\/a><figcaption><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Aten\u00e7\u00e3o concurseiros! Publicada a\u00a0convoca\u00e7\u00e3o\u00a0de mais excedentes para a realiza\u00e7\u00e3o da\u00a0matr\u00edcula\u00a0na segunda turma do Curso de Forma\u00e7\u00e3o Profissional no\u00a0concurso PF, o or\u00e7amento agora foi aprovado, veja! Confira:\u00a0Guia como montar um mapa mental (Gr\u00e1tis) Estude para o concurso dos seus sonhos com a\u00a0Assinatura Completa da Nova. Tenha acesso a Cursos, Plataforma de Quest\u00f5es, Eventos Exclusivos para Assinantes [&hellip;]<\/p>\n","protected":false},"author":54671,"featured_media":161096,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-163471","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/163471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54671"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=163471"}],"version-history":[{"count":8,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/163471\/revisions"}],"predecessor-version":[{"id":163516,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/163471\/revisions\/163516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/161096"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=163471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=163471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=163471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}