{"id":166680,"date":"2022-07-28T11:12:51","date_gmt":"2022-07-28T14:12:51","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=166680"},"modified":"2022-07-28T11:12:54","modified_gmt":"2022-07-28T14:12:54","slug":"concurso-ppgg-df-iades-e-a-banca-oferta-vagas-imediatas","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-ppgg-df-iades-e-a-banca-oferta-vagas-imediatas\/","title":{"rendered":"Concurso PPGG DF: Iades \u00e9 a banca. Oferta de 100 vagas imediatas!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aten\u00e7\u00e3o concurseiros! Um novo\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-ppgg-df\/\">concurso PPGG DF<\/a> (Pol\u00edticas P\u00fablicas e Gest\u00e3o Governamental do Distrito Federal)\u00a0est\u00e1 cada vez <strong>mais pr\u00f3ximo<\/strong>. A banca organizadora foi confirmada. Ser\u00e3o ofertadas <strong>100 vagas imediatas!<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Confira:<\/strong>\u00a0<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/www.novaconcursos.com.br\/eventos\/guia-definitivo-como-montar-um-mapa-mental\/\" target=\"_blank\">Guia Definitivo Como montar um mapa mental (Gr\u00e1tis)<\/a><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estude para o concurso dos seus sonhos com o\u00a0<strong>M\u00e9todo<\/strong>\u00a0que j\u00e1 ajudou na\u00a0<strong>aprova\u00e7\u00e3o de mais de 70 mil alunos.<\/strong>\u00a0<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/aprovacao.novaconcursos.com.br\/assinatura\" target=\"_blank\">Clique aqui<\/a>\u00a0e saiba mais!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-ppgg-df-quando-sai-o-edital\">Concurso PPGG DF: quando sai o edital?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 o que os concurseiros querem saber! Portanto, um novo <strong>concurso <\/strong>para as Pol\u00edticas P\u00fablicas e Gest\u00e3o Governamental do <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-previstos\/df\/\">Distrito Federal <\/a><strong>est\u00e1 perto <\/strong>de ser publicado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isso porque o Di\u00e1rio Oficial do DF desta quinta-feira (28) trouxe a publica\u00e7\u00e3o da confirma\u00e7\u00e3o da <strong>banca <\/strong>organizadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, a dispensa de licita\u00e7\u00e3o confirmou o <strong>Iades <\/strong>como respons\u00e1vel pelo edital da sele\u00e7\u00e3o.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale destacar, entretanto, que ser\u00e3o ofertadas<strong> 100 vagas <\/strong>imediatas para o cargo de\u00a0<strong>Gestor em Pol\u00edticas P\u00fablicas e Gest\u00e3o Governamental<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, o concurso ainda dever\u00e1 ofertar outras <strong>300 vagas<\/strong> para forma\u00e7\u00e3o de um <strong>cadastro reserva<\/strong> ao mesmo cargo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">E vagas para Analistas?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o, a portaria de autoriza\u00e7\u00e3o do concurso apresentava a <strong>previs\u00e3o de 150 vagas<\/strong> para o cargo de <strong>Analista <\/strong>em Pol\u00edticas P\u00fablicas e Gest\u00e3o Governamental.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, o documento publicado confirmando a banca <strong>n\u00e3o informa o provimento <\/strong>de vagas para a carreira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, \u00e9 importante destacar que o <strong>cargo est\u00e1 previsto<\/strong> no or\u00e7amento deste ano de 2022.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pr\u00f3xima etapa<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Com a banca confirmada, a <strong>expectativa <\/strong>agora fica pela produ\u00e7\u00e3o e publica\u00e7\u00e3o do edital, que ser\u00e1 o <strong>primeiro <\/strong>para a carreira no <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/df\/\">Distrito Federal<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">E os sal\u00e1rios?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o Portal de Transpar\u00eancia do DF, o sal\u00e1rio inicial do cargo de Gestor em Pol\u00edticas P\u00fablicas \u00e9 de\u00a0<strong>R$ 7.760,00<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretanto, j\u00e1 ao final da carreira, a remunera\u00e7\u00e3o do servidor passa a ser de\u00a0<strong>R$ 10.194,22<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, os valores se referem a uma jornada de trabalho de <strong>40 horas <\/strong>semanais. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas, para uma jornada de <strong>30h semanais<\/strong>, os valores s\u00e3o de <strong>R$ 5.820,00 <\/strong>(inicial) e <strong>R$ 7.645,66<\/strong> (final), respectivamente. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Requisitos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 importante que os interessados no certame saibam que devem possuir diploma de <strong>n\u00edvel superior de gradua\u00e7\u00e3o. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Atribui\u00e7\u00f5es<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, os concurseiros devem <strong>conhecer as atribui\u00e7\u00f5es <\/strong>da carreira, para que possa participar da sele\u00e7\u00e3o e ingressar no \u00f3rg\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, s\u00e3o respons\u00e1veis por formular, planejar, coordenar, supervisionar e avaliar atividades relacionadas \u00e0 gest\u00e3o governamental de pol\u00edticas p\u00fablicas nos diversos \u00f3rg\u00e3os da Administra\u00e7\u00e3o Direta, relativamente aut\u00f4nomos, especializados, funda\u00e7\u00f5es p\u00fablicas e autarquias, inclusive de regime especial; executar outras atividades de mesma natureza e n\u00edvel de complexidade determinadas em legisla\u00e7\u00e3o espec\u00edfica, observadas as peculiaridades da especialidade do cargo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/aprovacao.novaconcursos.com.br\/assinatura\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2022\/01\/Faixa-Frete-Gr%E2%80%A0tis-portal.png\" alt=\"assinatura completa\" class=\"wp-image-153078\" loading=\"lazy\" title=\"\"><\/a><figcaption><\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Aten\u00e7\u00e3o concurseiros! Um novo\u00a0concurso PPGG DF (Pol\u00edticas P\u00fablicas e Gest\u00e3o Governamental do Distrito Federal)\u00a0est\u00e1 cada vez mais pr\u00f3ximo. A banca organizadora foi confirmada. Ser\u00e3o ofertadas 100 vagas imediatas! Confira:\u00a0Guia Definitivo Como montar um mapa mental (Gr\u00e1tis) Estude para o concurso dos seus sonhos com o\u00a0M\u00e9todo\u00a0que j\u00e1 ajudou na\u00a0aprova\u00e7\u00e3o de mais de 70 mil alunos.\u00a0Clique aqui\u00a0e [&hellip;]<\/p>\n","protected":false},"author":54671,"featured_media":166681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-166680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/166680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54671"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=166680"}],"version-history":[{"count":6,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/166680\/revisions"}],"predecessor-version":[{"id":166688,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/166680\/revisions\/166688"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/166681"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=166680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=166680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=166680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}