{"id":17976,"date":"2015-04-28T11:56:58","date_gmt":"2015-04-28T14:56:58","guid":{"rendered":"http:\/\/www.novaconcursos.com.br\/portal\/?p=17976"},"modified":"2021-01-28T14:59:01","modified_gmt":"2021-01-28T17:59:01","slug":"analise-de-edital-dpu-2015","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/analise-de-edital-dpu-2015\/","title":{"rendered":"An\u00e1lise de edital: DPU 2015"},"content":{"rendered":"<p><a href=\"https:\/\/www.novaconcursos.com.br\/apostila-concurso\/dpu-defensoria-publica-da-uniao\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" class=\" size-full wp-image-28347 alignleft\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2015\/10\/dpu-250X250.jpg\" alt=\"dpu-250X250\" width=\"250\" height=\"250\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2015\/10\/dpu-250X250-55x55.jpg 55w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2015\/10\/dpu-250X250-105x105.jpg 105w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2015\/10\/dpu-250X250-150x150.jpg 150w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2015\/10\/dpu-250X250.jpg 250w\" sizes=\"auto, (max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1200px) 70vw, 768px\"><\/a>A Defensoria P\u00fablica da Uni\u00e3o (DPU) acaba de lan\u00e7ar edital para concurso p\u00fablico e o Grupo Nova destrincha os principais pontos deste edital para voc\u00ea!<\/p>\n<p><strong>Vagas:<\/strong> s\u00e3o 143 oportunidades e forma\u00e7\u00e3o de cadastro de reserva para candidatos com n\u00edveis m\u00e9dio e superior.<\/p>\n<p><strong>Garanta j\u00e1 a sua vaga neste concurso!<\/strong><br><a href=\"https:\/\/www.novaconcursos.com.br\/apostila-concurso\/dpu-defensoria-publica-da-uniao\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Compre aqui: Apostila DPU<br><\/strong><\/a><a href=\"https:\/\/www.novaconcursos.com.br\/curso-online\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Compre aqui: Curso Online\u00a0DPU<\/strong><\/a><\/p>\n<p><strong>Sal\u00e1rios:<\/strong> a remunera\u00e7\u00e3o varia de R$3.817,98 a R$6.348,27, dependendo do cargo pretendido. A carga de trabalho \u00e9 de 40h semanais<\/p>\n<p><strong>Inscri\u00e7\u00f5es:<\/strong> as inscri\u00e7\u00f5es come\u00e7am no dia 22 de abril de 2015 e v\u00e3o at\u00e9 11 de maio, e podem ser feitas no site da Cespe\/UnB, banca organizadora do certame. As taxas s\u00e3o de R$ 70 (n\u00edvel m\u00e9dio) e R$ 100 (n\u00edvel superior).<\/p>\n<p><strong>Prova:<\/strong> os testes objetivos est\u00e3o agendados para o dia 21 de junho e ser\u00e3o aplicados em todas as capitais de estado e Distrito Federal.<\/p>\n<p>A validade inicial do concurso \u00e9 de um ano.<\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>A Defensoria P\u00fablica da Uni\u00e3o (DPU) acaba de lan\u00e7ar edital para concurso p\u00fablico e o Grupo Nova destrincha os principais pontos deste edital para voc\u00ea! Vagas: s\u00e3o 143 oportunidades e forma\u00e7\u00e3o de cadastro de reserva para candidatos com n\u00edveis m\u00e9dio e superior. Garanta j\u00e1 a sua vaga neste concurso!Compre aqui: Apostila DPUCompre aqui: Curso Online\u00a0DPU [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":9728,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[12674,12675,1137,1115,1117,574,12676,12677,1118,1071,1138,2326,5388,12678,1074,12679,12680,1075,1076,12681,12682,12683,12684,12685],"class_list":["post-17976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-analise-de-edital-defensoria-publica-da-uniao","tag-analise-de-edital-dpu","tag-apostila-defensoria-publica-da-uniao","tag-apostila-dpu","tag-apostila-dpu-2015","tag-apostila-para-concurso","tag-concurso-aberto-defensoria-publica-da-uniao","tag-concurso-aberto-dpu","tag-concurso-defensoria-publica-da-uniao","tag-concurso-dpu","tag-concurso-dpu-2015","tag-concurso-publico","tag-concurso-publico-dpu","tag-conteudo-programatico-dpu","tag-defensoria-publica-da-uniao","tag-dicas-prova-defensoria-publica-da-uniao","tag-dicas-prova-dpu","tag-dpu","tag-dpu-2015","tag-o-que-cai-na-prova-defensoria-publica-da-uniao","tag-o-que-cai-na-prova-dpu","tag-prova-defensoria-publica-da-uniao","tag-saiu-o-edital-defensoria-publica-da-uniao","tag-saiu-o-edital-dpu-2015"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/17976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=17976"}],"version-history":[{"count":5,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/17976\/revisions"}],"predecessor-version":[{"id":112966,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/17976\/revisions\/112966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/9728"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=17976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=17976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=17976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}