{"id":186918,"date":"2023-02-27T11:38:04","date_gmt":"2023-02-27T14:38:04","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=186918"},"modified":"2023-02-27T11:38:09","modified_gmt":"2023-02-27T14:38:09","slug":"concurso-brb-resultado-final-publicado-confira-o-nome-dos-aprovados","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-brb-resultado-final-publicado-confira-o-nome-dos-aprovados\/","title":{"rendered":"Concurso BRB: Resultado final publicado. Confira o nome dos aprovados!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Foram divulgados os resultados finais do\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-brb\/\">concurso BRB<\/a>, que est\u00e1 ofertando um total de 500 vagas para\u00a0<strong>Escritur\u00e1rio<\/strong>, sendo 300 vagas imediatas e 200 oportunidades de cadastro reserva.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Confira:\u00a0<\/strong><a href=\"https:\/\/www.novaconcursos.com.br\/livro\/1000-questoes-gabaritadas-brb-escriturario\">Livro 1.000 Quest\u00f5es Gabaritadas BRB \u2013 Escritur\u00e1rio<\/a><\/li><li><strong>Confira:\u00a0<\/strong><a href=\"https:\/\/www.novaconcursos.com.br\/apostila\/brb-escriturario\">Apostila BRB 2022 \u2013 Escritur\u00e1rio<\/a><\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estude para o concurso dos seus sonhos com o\u00a0<strong>M\u00e9todo<\/strong>\u00a0que j\u00e1 ajudou na\u00a0<strong>aprova\u00e7\u00e3o de mais de 70 mil alunos.<\/strong>\u00a0<a rel=\"noreferrer noopener\" aria-label=\" (abre numa nova aba)\" href=\"https:\/\/aprovacao.novaconcursos.com.br\/assinatura\" target=\"_blank\">Clique aqui<\/a>\u00a0e saiba mais!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-brb-como-conferir-o-resultado\">Concurso BRB: como conferir o resultado?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, o <strong>resultado final<\/strong> do concurso do Banco Regional de Bras\u00edlia, no\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-previstos\/df\/\">Distrito Federal<\/a>\u00a0foi publicado, enfim.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vale lembrar que as <strong>provas\u00a0<\/strong>objetivas foram aplicadas no \u00faltimo dia 6 de novembro de 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o documento com a lista de <strong>aprovados <\/strong>foi divulgado no Di\u00e1rio Oficial do DF desta segunda-feira (27\/02).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ademais, a <strong>rela\u00e7\u00e3o <\/strong>dos aprovados foi realizada com n\u00famero de inscri\u00e7\u00e3o, nome completo por ordem de classifica\u00e7\u00e3o, nota final no concurso p\u00fablico, classifica\u00e7\u00e3o ampla concorr\u00eancia, classifica\u00e7\u00e3o PcD, classifica\u00e7\u00e3o PNP e classifica\u00e7\u00e3o Hipossuficiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" aria-label=\"Confira o resultado, clicando aqui! (abre numa nova aba)\" href=\"https:\/\/www.iades.com.br\/inscricao\/upload\/307\/2023022710325151.pdf\" target=\"_blank\">Confira o resultado, clicando aqui!<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"vagas-ofertadas-no-concurso-brb\">Vagas ofertadas no concurso BRB<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Assim, o concurso do Banco Regional de Bras\u00edlia, no\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/df\/\">Distrito Federal<\/a>,\u00a0est\u00e1 ofertando <strong>500 vagas, sendo 300 imediatas e 200 para cadastro reserva<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Portanto, todas as vagas s\u00e3o\u00a0<strong>para o cargo de\u00a0Escritur\u00e1rio<\/strong>, carreira que exige apenas o\u00a0<strong>n\u00edvel m\u00e9dio<\/strong>\u00a0e tem jornada de\u00a0trabalho de 30 horas semanais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, h\u00e1\u00a0<strong>reserva de vagas<\/strong>\u00a0destinada \u00e0s cotas, para pessoas com defici\u00eancia, hipossuficientes, negros, \u00edndios e quilombolas.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, ser\u00e3o remunerados com sal\u00e1rios iniciais no valor de\u00a0<strong>3.764,66<\/strong>\u00a0+ benef\u00edcios. Veja!<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Participa\u00e7\u00e3o nos lucros e nos resultados;<\/li><li>Plano de sa\u00fade;<\/li><li>Previd\u00eancia complementar;<\/li><li>Aux\u00edlios refei\u00e7\u00e3o\/alimenta\u00e7\u00e3o;<\/li><li>Cesta alimenta\u00e7\u00e3o;<\/li><li>Aux\u00edlios natalidade e creche;<\/li><li>Licen\u00e7as maternidade e paternidade estendidas;<\/li><li>Incentivos educacionais.<\/li><\/ul><p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Requisitos<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>N\u00e3o estar em licen\u00e7a, ainda que n\u00e3o remunerada, de cargo ou emprego p\u00fablico que exer\u00e7a na administra\u00e7\u00e3o direta ou indireta da Uni\u00e3o, Estados, Distrito Federal e Munic\u00edpios.<\/li><li>N\u00e3o ser servidor p\u00fablico que tenha solicitado vac\u00e2ncia do cargo p\u00fablico que ocupa por outros motivos que n\u00e3o sejam exonera\u00e7\u00e3o ou demiss\u00e3o.<\/li><li>Ter idade m\u00ednima de 16 (dezesseis) anos completos na data de contrata\u00e7\u00e3o, conforme Decis\u00e3o no 7.949\/2009 do Tribunal de Contas do Distrito Federal.<\/li><li>N\u00e3o ser aposentado pelo INSS ou servidor p\u00fablico aposentado, ressalvadas as possibilidades de acumula\u00e7\u00e3o l\u00edcita de cargos, fun\u00e7\u00f5es, empregos ou proventos de aposentadoria, a teor do disposto no art. 37, inciso XVI, da Constitui\u00e7\u00e3o Federal.<\/li><li>N\u00e3o ser s\u00f3cio, s\u00f3cio\/gerente, s\u00f3cio\/cotista ou participante de conselho e\/ou administra\u00e7\u00e3o de organiza\u00e7\u00e3o banc\u00e1ria ou qualquer outra empresa concorrente do BRB.<\/li><li>Ser brasileiro nato ou naturalizado ou cidad\u00e3o portugu\u00eas que tenha adquirido a igualdade de direitos e obriga\u00e7\u00f5es civis e o gozo dos direitos pol\u00edticos (Decreto Federal no 70.436, de 18 de abril de 1972, e Constitui\u00e7\u00e3o Federal).<\/li><li>N\u00e3o manter rela\u00e7\u00e3o de emprego com incompatibilidade de hor\u00e1rio com a jornada de trabalho no BRB.<\/li><li>N\u00e3o manter rela\u00e7\u00e3o de emprego, ainda que de natureza t\u00e9cnica ou especializada, em institui\u00e7\u00e3o integrante do Sistema Financeiro Nacional, em empresa que ofere\u00e7a produtos e\/ou servi\u00e7os concorrentes aos do BRB ou em empresa prestadora de servi\u00e7o para organiza\u00e7\u00e3o concorrente do BRB.<\/li><li>Cumprir as determina\u00e7\u00f5es deste edital, ter sido aprovado neste concurso p\u00fablico considerado apto nos exames m\u00e9dicos admissionais.<\/li><li>Entre outros.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Foram divulgados os resultados finais do\u00a0concurso BRB, que est\u00e1 ofertando um total de 500 vagas para\u00a0Escritur\u00e1rio, sendo 300 vagas imediatas e 200 oportunidades de cadastro reserva. Confira:\u00a0Livro 1.000 Quest\u00f5es Gabaritadas BRB \u2013 Escritur\u00e1rio Confira:\u00a0Apostila BRB 2022 \u2013 Escritur\u00e1rio Estude para o concurso dos seus sonhos com o\u00a0M\u00e9todo\u00a0que j\u00e1 ajudou na\u00a0aprova\u00e7\u00e3o de mais de 70 mil [&hellip;]<\/p>\n","protected":false},"author":54671,"featured_media":156195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-186918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/186918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54671"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=186918"}],"version-history":[{"count":6,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/186918\/revisions"}],"predecessor-version":[{"id":186925,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/186918\/revisions\/186925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/156195"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=186918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=186918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=186918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}