{"id":207191,"date":"2023-10-05T09:12:44","date_gmt":"2023-10-05T12:12:44","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=207191"},"modified":"2023-10-05T09:12:47","modified_gmt":"2023-10-05T12:12:47","slug":"concurso-caixa-presidente-estatal-preve-edital-inicio-proximo-ano","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-caixa-presidente-estatal-preve-edital-inicio-proximo-ano\/","title":{"rendered":"Concurso Caixa: Presidente da estatal prev\u00ea edital at\u00e9 in\u00edcio do pr\u00f3ximo ano!"},"content":{"rendered":"<p>Boa not\u00edcia para aqueles que est\u00e3o aguardando o <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-caixa-economica-federal\/\">concurso Caixa.<\/a> A presidente do banco, Rita Serrano, prev\u00ea edital no in\u00edcio do <strong>ano que vem, <\/strong>em 2024.<\/p>\n\n\n\n<p>A informa\u00e7\u00e3o foi repassada nesta quarta-feira, 4 de outubro,\u00a0durante entrevista coletiva transmitida pelo Canal do Bar\u00e3o.<\/p>\n\n\n\n<p><em>\u201cEu espero que seja at\u00e9 o in\u00edcio do ano que vem\u201d<\/em>, destacou a presidenta.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A expectativa pela realiza\u00e7\u00e3o do novo concurso cresceu depois da\u00a0<strong>convoca\u00e7\u00e3o de mais\u00a0800 aprovados\u00a0<\/strong>no\u00a0\u00faltimo concurso, realizado em 2014.<\/p>\n\n\n\n<p>As nomea\u00e7\u00f5es ser\u00e3o efetuadas ainda nesse m\u00eas de outubro, viabilizando a publica\u00e7\u00e3o de um<strong> novo edital. <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Confira:<\/strong> <a href=\"https:\/\/www.novaconcursos.com.br\/apostila\/caixa-economica-federal-tecnico-bancario?q=caixa\">Apostila Caixa Econ\u00f4mica Federal 2023 \u2013 T\u00e9cnico Banc\u00e1rio<\/a><\/li>\n\n\n\n<li><strong>Confira:<\/strong> <a href=\"https:\/\/www.novaconcursos.com.br\/curso-online\/caixa-economica-federal-tec-bancario?q=caixa\">Curso Online Caixa Econ\u00f4mica Federal \u2013 T\u00e9cnico Banc\u00e1rio<\/a><\/li>\n<\/ul><p><\/p>\n\n\n\n<p>Estude para o concurso dos seus sonhos com o\u00a0<strong>M\u00e9todo<\/strong>\u00a0que j\u00e1 ajudou na\u00a0<strong>aprova\u00e7\u00e3o de mais de 70 mil alunos.<\/strong>\u00a0<a href=\"https:\/\/aprovacao.novaconcursos.com.br\/assinatura?promo_creative=Clique+aqui&amp;promo_name=noticia&amp;promo_id=%2Fportal%2Fnoticias%2Fconcurso-pc-sp-ultimos-dias-de-inscricao&amp;promo_position=corpo-texto\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui<\/a>\u00a0e saiba mais!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"por-que-os-aprovados-em-2014-s-esto-sendo-convocados-em-2023\">Por que os aprovados em 2014 s\u00f3 est\u00e3o sendo convocados em 2023?<\/h2>\n\n\n\n<p>Apesar do n\u00famero de aprovados no concurso de 2014 ter ultrapassado a casa dos 30 mil, o \u00f3rg\u00e3o convocou<strong>\u00a0menos de 8% da lista.<\/strong><\/p>\n\n\n\n<p>Por isso, o Minist\u00e9rio P\u00fablico do Trabalho protocolou uma A\u00e7\u00e3o Civil P\u00fablica (ACP) solicitando as nomea\u00e7\u00f5es e garantindo que o edital\u00a0<strong>permane\u00e7a v\u00e1lido at\u00e9 decis\u00e3o judicial final.<\/strong><\/p>\n\n\n\n<p>Em outras palavras, o \u00faltimo concurso segue vigente enquanto n\u00e3o forem esgotados todos os\u00a0<strong>recursos judiciais\u00a0<\/strong>referentes \u00e0 contrata\u00e7\u00e3o dos aprovados em 2014.<\/p>\n\n\n\n<p>Deste ent\u00e3o, mais de\u00a0<strong>6 mil classificados foram nomeados<\/strong> e a convoca\u00e7\u00e3o desses 800 aprovados marca o fim do prazo de validade do concurso.<\/p>\n\n\n\n<p><em>\u201cDesde quando eu era conselheira de administra\u00e7\u00e3o do banco, eu vinha batalhando para contratar mais empregados. Dessa forma, vamos melhorar as condi\u00e7\u00f5es de trabalho, o atendimento \u00e0 popula\u00e7\u00e3o e, assim, vamos construindo uma nova Caixa para um novo Brasil\u201d,\u00a0<\/em>disse a presidenta, Rita Serrano.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"programa-de-demisso-voluntria-viabiliza-novo-concurso-caixa\">Programa de Demiss\u00e3o Volunt\u00e1ria viabiliza novo concurso Caixa!<\/h2>\n\n\n\n<p>Al\u00e9m das convoca\u00e7\u00f5es, o banco est\u00e1 se preparando para um novo Programa de Demiss\u00e3o Volunt\u00e1ria (PDV).<\/p>\n\n\n\n<p>A ades\u00e3o dos funcion\u00e1rios ao programa pode estabelecer uma<strong> s\u00e9rie de vac\u00e2ncias,<\/strong> sendo necess\u00e1ria a <strong>recomposi\u00e7\u00e3o do quadro de pessoal.<\/strong><\/p>\n\n\n\n<p>No \u00faltimo PDV realizado, foi necess\u00e1rio preencher os seguintes requisitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Estar aposentado antes de 13 de novembro de 2019 (quando entrou em vigor a reforma da Previd\u00eancia);<\/li>\n\n\n\n<li>Estar apto para se aposentar at\u00e9 31 de dezembro de 2020, que solicitassem a aposentadoria ao INSS ap\u00f3s 6 de novembro de 2020;<\/li>\n\n\n\n<li>Receber o adicional de incorpora\u00e7\u00e3o; <\/li>\n\n\n\n<li>Ter 15 anos ou mais de Caixa.<\/li>\n<\/ul><p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"como-foi-o-concurso-caixa-2014\">Como foi o concurso Caixa 2014?<\/h2>\n\n\n\n<p>O <a href=\"http:\/\/www.cespe.unb.br\/concursos\/CAIXA_14_NM\/arquivos\/ED_1_CAIXA_2014_NM___EDITAL_DE_ABERTURA__SEM_ANEXO_2_.PDF\" target=\"_blank\" rel=\"noreferrer noopener\">concurso Caixa de 2014<\/a> foi um dos maiores certames j\u00e1 realizados. Ao todo, foram registradas quase\u00a0<strong>1,2 milh\u00e3o de candidaturas,<\/strong>\u00a0onde 32.879 candidatos foram aprovados.<\/p>\n\n\n\n<p>Foram ofertadas oportunidades de<strong>\u00a0T\u00e9cnico Banc\u00e1rio<\/strong> para forma\u00e7\u00e3o de um cadastro reserva.<\/p>\n\n\n\n<p>Na ocasi\u00e3o, os candidatos foram\u00a0<strong>avaliados\u00a0<\/strong>por meio das seguintes etapas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1\u00aa etapa: prova objetiva e prova discursiva, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio;<\/li>\n\n\n\n<li>2\u00aa etapa: exames m\u00e9dicos admissionais, de car\u00e1ter eliminat\u00f3rio.<\/li>\n<\/ul><p><\/p>\n\n\n\n<p>A prova objetiva foi composta de<strong>\u00a0120 quest\u00f5es<\/strong>\u00a0de julgamento, do estilo \u201cCERTO\u201d ou \u201cERRADO\u201d, sobre as disciplinas de:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>L\u00edngua Portuguesa;<\/li>\n\n\n\n<li>Matem\u00e1tica;<\/li>\n\n\n\n<li>Racioc\u00ednio L\u00f3gico;<\/li>\n\n\n\n<li>Atualidades;<\/li>\n\n\n\n<li>\u00c9tica;<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o Espec\u00edfica;<\/li>\n\n\n\n<li>Conhecimentos Espec\u00edficos.<\/li>\n<\/ul><p><\/p>\n\n\n\n<p><strong>Leia tamb\u00e9m:<\/strong> <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/artigos\/concurso-caixa-2023-o-que-estudar-para-tecnico-bancario\/\">Concurso Caixa: O que estudar para T\u00e9cnico?<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quanto-ganha-um-tcnico-bancrio-da-caixa\">Quanto ganha um T\u00e9cnico Banc\u00e1rio da Caixa?<\/h2>\n\n\n\n<p>A carreira exige o\u00a0<strong>n\u00edvel m\u00e9dio<\/strong>\u00a0e oferece\u00a0<strong>remunera\u00e7\u00e3o inicial\u00a0<\/strong>no valor de R$ 3.000,00, al\u00e9m de v\u00e1rios benef\u00edcios, como:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Participa\u00e7\u00e3o nos lucros ou resultados;<\/li>\n\n\n\n<li>Vale-transporte;<\/li>\n\n\n\n<li>Aux\u00edlio-refei\u00e7\u00e3o\/alimenta\u00e7\u00e3o;<\/li>\n\n\n\n<li>Aux\u00edlio-creche;<\/li>\n\n\n\n<li>Previd\u00eancia complementar;<\/li>\n\n\n\n<li>Possibilidade de ascens\u00e3o profissional;<\/li>\n\n\n\n<li>Acesso a a\u00e7\u00f5es de capacita\u00e7\u00e3o e desenvolvimento.<\/li>\n<\/ul><p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"seja-voc-o-prximo-aluno-a-aprovado\">Seja voc\u00ea o pr\u00f3ximo aluno (a) aprovado!<\/h2>\n\n\n\n<p>Como voc\u00ea viu, um novo concurso Caixa ser\u00e1 realizado em breve. Ent\u00e3o, n\u00e3o perca tempo em iniciar sua prepara\u00e7\u00e3o e fique na frente de seus concorrentes!<\/p>\n\n\n\n<p>Os\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/?promo_creative=materiais+da+Nova&amp;promo_name=artigo&amp;promo_id=%2Fportal%2Fartigos%2Fconcurso-caixa-2023-o-que-estudar-para-tecnico-bancario&amp;promo_position=corpo-texto\">materiais da Nova<\/a>\u00a0s\u00e3o uma \u00f3tima fonte de conhecimento. Isso porque al\u00e9m de atualizados, eles s\u00e3o direto ao ponto e foram produzidos por<strong>\u00a0professores que s\u00e3o refer\u00eancia no mercado.<\/strong><\/p>\n\n\n\n<p>Nos preocupamos com a sua aprendizagem, por isso oferecemos materiais em diversos formatos, como apostila, curso online, livro de quest\u00f5es, dentre outros.<\/p>\n\n\n\n<p>E o melhor de tudo, materiais que se<strong>\u00a0encaixam no seu or\u00e7amento e tempo<\/strong> \u2705<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Adquira:<\/strong>\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/livro\/caderno-1000-questoes-gabaritadas-caixa?promo_creative=Caderno+1.000+Quest%C3%B5es+Gabaritadas+para+Caixa&amp;promo_name=noticia&amp;promo_id=%2Fportal%2Fnoticias%2Fconcurso-caixa-800-aprovados-convocados&amp;promo_position=corpo-texto\">Caderno 1.000 Quest\u00f5es Gabaritadas para Caixa<\/a><\/li>\n<\/ul><p><\/p>\n\n\n\n<p>J\u00e1 s\u00e3o mais de <strong>70 mil alunos<\/strong> aprovados! ?<\/p>\n\n\n\n<p>Para mais dicas, d\u00e1 o play no v\u00eddeo do professor Heitor Ferreira e saiba como ser aprovado estudando 1 hora por dia! ?<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Concurso Caixa 2023 Plano de Estudos [1 HORA POR DIA]\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/PPox8tqRi98?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>Boa not\u00edcia para aqueles que est\u00e3o aguardando o concurso Caixa. A presidente do banco, Rita Serrano, prev\u00ea edital no in\u00edcio do ano que vem, em 2024. A informa\u00e7\u00e3o foi repassada nesta quarta-feira, 4 de outubro,\u00a0durante entrevista coletiva transmitida pelo Canal do Bar\u00e3o. \u201cEu espero que seja at\u00e9 o in\u00edcio do ano que vem\u201d, destacou a [&hellip;]<\/p>\n","protected":false},"author":54679,"featured_media":157928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-207191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/207191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54679"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=207191"}],"version-history":[{"count":18,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/207191\/revisions"}],"predecessor-version":[{"id":207217,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/207191\/revisions\/207217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/157928"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=207191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=207191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=207191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}