{"id":243192,"date":"2024-07-09T11:54:12","date_gmt":"2024-07-09T14:54:12","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=243192"},"modified":"2024-11-08T16:42:32","modified_gmt":"2024-11-08T19:42:32","slug":"concurso-trt-rj-edital-autorizado","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-trt-rj-edital-autorizado\/","title":{"rendered":"TRT RJ 2024: Edital autorizado para T\u00e9cnicos e Analistas Judici\u00e1rios!"},"content":{"rendered":"<p>O <strong><a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-trt-rj-1a-regiao\/\">concurso TRT RJ<\/a> tem edital autorizado para T\u00e9cnicos e Analistas Judici\u00e1rios<\/strong>, de n\u00edvel superior de escolaridade.<\/p>\n\n\n\n<p>O sal\u00e1rio no Tribunal Regional do Trabalho da 1\u00aa Regi\u00e3o poder\u00e1 chegar at\u00e9 R$15.387,88!<\/p>\n\n\n\n<p>Se interessa pelo certame? Fique e confira os demais detalhes sobre o <em>edital autorizado para T\u00e9cnicos e Analistas Judici\u00e1rios do concurso TRT RJ!<\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quando-o-edital-do-concurso-trt-rj-poder-ser-publicado\">Quando o edital do concurso TRT RJ poder\u00e1 ser publicado?<\/h2>\n\n\n\n<p>Na noite desta segunda-feira, 8 de julho, o Tribunal Regional do Trabalho da 1\u00aa Regi\u00e3o (TRT RJ) oficializou a autoriza\u00e7\u00e3o para a realiza\u00e7\u00e3o do concurso p\u00fablico destinado \u00e0 \u00e1rea de Apoio. A decis\u00e3o foi formalizada por meio da Resolu\u00e7\u00e3o Administrativa n\u00ba 19\/2024, publicada no Di\u00e1rio Eletr\u00f4nico do tribunal.<\/p>\n\n\n\n<p>O certame, que ter\u00e1 validade inicial de dois anos, podendo ser prorrogado por mais dois, conforme estabelecido na resolu\u00e7\u00e3o, ser\u00e1 coordenado por um Conselho Deliberativo. Este ser\u00e1 presidido pelo desembargador Leonardo da Silveira Pacheco, tendo como suplente o desembargador Jos\u00e9 Luis Campos Xavier.<\/p>\n\n\n\n<p>Integram tamb\u00e9m o Conselho a secret\u00e1ria da Escola Judicial Marina Leite Ribeiro, a coordenadora de Ensino e Pesquisas Let\u00edcia Morais de Franca Oliveira, e a diretora da Secretaria de Gest\u00e3o de Pessoas, Renata de Azevedo Amancio.<\/p>\n\n\n\n<p>Desde abril, uma comiss\u00e3o respons\u00e1vel pelo concurso, denominada Equipe de Planejamento e Contrata\u00e7\u00e3o, est\u00e1 em atividade. A equipe \u00e9 liderada por Cl\u00e1udio Braga Martins, com Ellen Cardoso Teixeira Pinto como coordenadora substituta e S\u00f4nia Regina de Freitas Andrade atuando como integrante administrativa.<\/p>\n\n\n\n<p>Confira o documento na \u00edntegra:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2024\/07\/Concurso-TRT-RJ-tem-edital-autorizado.webp\"><img decoding=\"async\" width=\"728\" height=\"480\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2024\/07\/Concurso-TRT-RJ-tem-edital-autorizado.webp\" alt=\"Extrato de autoriza\u00e7\u00e3o do edital para o concurso TRT RJ\" class=\"wp-image-243198\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2024\/07\/Concurso-TRT-RJ-tem-edital-autorizado-300x198.webp 300w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2024\/07\/Concurso-TRT-RJ-tem-edital-autorizado-480x316.webp 480w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2024\/07\/Concurso-TRT-RJ-tem-edital-autorizado.webp 728w\" sizes=\"auto, (max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1200px) 70vw, 768px\"><\/a><figcaption class=\"wp-element-caption\">Concurso TRT RJ tem edital autorizado para T\u00e9cnicos e Analistas Judici\u00e1rios.<\/figcaption><\/figure><p>O pr\u00f3ximo passo do TRT RJ \u00e9 a defini\u00e7\u00e3o da banca organizadora do concurso. Diversas empresas j\u00e1 apresentaram suas propostas, incluindo o Idecan, e o tribunal j\u00e1 iniciou o processo de sele\u00e7\u00e3o da institui\u00e7\u00e3o respons\u00e1vel.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es, o TRT RJ est\u00e1 se organizando para minimizar o intervalo entre o t\u00e9rmino da validade do \u00faltimo concurso e a realiza\u00e7\u00e3o do novo certame, com previs\u00e3o para lan\u00e7amento do edital, recebimento de inscri\u00e7\u00f5es e aplica\u00e7\u00e3o das provas, que podem ocorrer at\u00e9 agosto.<\/p>\n\n\n\n<p>Estude para o concurso dos seus sonhos com o\u00a0M\u00e9todo\u00a0que j\u00e1 ajudou na\u00a0aprova\u00e7\u00e3o de mais de 70 mil alunos!\u00a0<a href=\"https:\/\/www.novaconcursos.com.br\/eventos\/assinatura\/?promo_creative=Clique+aqui&amp;promo_name=concurso&amp;promo_id=%2Fportal%2Fconcursos%2Fconcurso-mte&amp;promo_position=corpo-texto\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui<\/a>\u00a0e saiba mais!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quais-sero-os-cargos-ofertados-no-concurso-trt-rj\">Quais ser\u00e3o os cargos ofertados no concurso TRT RJ?<\/h2>\n\n\n\n<p>Segundo a autoriza\u00e7\u00e3o do concurso TRT RJ 2024 ofertar\u00e1 vagas para diversas especialidades. Confira quais s\u00e3o:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Analista Judici\u00e1rio<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Analista Judici\u00e1rio \u2013 \u00c1rea Judici\u00e1ria;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Judici\u00e1ria Especialidade: Oficial de Justi\u00e7a Avaliador Federal;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Administrativa \u2013 Especialidade: Contabilidade;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Arquivologia;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Biblioteconomia;<\/li>\n\n\n\n<li>\u00a0Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Enfermagem;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Engenharia Civil;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Engenharia El\u00e9trica;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Engenharia Mec\u00e2nica;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Estat\u00edstica;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Medicina;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Medicina Cardiologia;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Medicina do Trabalho;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Medicina Psiquiatria;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Psicologia;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Servi\u00e7o Social;<\/li>\n\n\n\n<li>Analista Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade: Tecnologia da Informa\u00e7\u00e3o;<\/li>\n<\/ul><h3 class=\"wp-block-heading\">T\u00e9cnico Judici\u00e1rio<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>T\u00e9cnico Judici\u00e1rio \u2013 \u00c1rea Administrativa; T\u00e9cnico Judici\u00e1rio \u2013 \u00c1rea Administrativa \u2013 Especialidade: Agente da Pol\u00edcia Judicial;<\/li>\n\n\n\n<li>T\u00e9cnico Judici\u00e1rio \u2013 \u00c1rea Apoio Especializado \u2013 Especialidade Enfermagem;<\/li>\n<\/ul><p>O n\u00famero de vagas a serem ofertadas ainda n\u00e3o foram divulgadas, contudo, sabe-se que o \u00f3rg\u00e3o possui atualmente 390 cargos vagos, sendo 25 cargos vagos para Analista e 365 cargos vagos para T\u00e9cnico, segundo informa\u00e7\u00f5es do portal de transpar\u00eancia.<\/p>\n\n\n\n\n\n<h2 class=\"wp-block-heading\" id=\"qual-ser-o-salrio-do-candidato-aprovado-no-concurso-trt-rj\">Qual ser\u00e1 o sal\u00e1rio do candidato aprovado no concurso TRT RJ?<\/h2>\n\n\n\n<p>O novo edital divulgado pelo Judici\u00e1rio revela detalhes sobre a remunera\u00e7\u00e3o dos servidores aprovados, composta pela soma do vencimento b\u00e1sico com gratifica\u00e7\u00f5es espec\u00edficas. Segundo o documento, os valores variam de acordo com a fun\u00e7\u00e3o exercida:<\/p>\n\n\n\n<p>Para os t\u00e9cnicos judici\u00e1rios, a remunera\u00e7\u00e3o alcan\u00e7a R$9.922,75, distribu\u00eddos entre R$3.554,02 de vencimento b\u00e1sico, R$4.975,64 de Gratifica\u00e7\u00e3o por Atividade Jur\u00eddica (GAJ), al\u00e9m de R$1.393,10 destinados ao aux\u00edlio-alimenta\u00e7\u00e3o.<\/p>\n\n\n\n<p>J\u00e1 para os t\u00e9cnicos judici\u00e1rios da pol\u00edcia judicial, o valor \u00e9 de R$11.166,66, sendo R$3.554,02 de vencimento b\u00e1sico, R$4.975,64 de GAJ, e uma Gratifica\u00e7\u00e3o de Atividades de Seguran\u00e7a (GAS) no valor de R$1.243,91, somados aos R$1.393,10 de aux\u00edlio-alimenta\u00e7\u00e3o.<\/p>\n\n\n\n<p>Para os analistas judici\u00e1rios, a remunera\u00e7\u00e3o \u00e9 de R$15.387,88, composta por R$5.831,15 de vencimento b\u00e1sico, R$8.163,61 de GAJ, al\u00e9m dos R$1.393,10 destinados ao aux\u00edlio-alimenta\u00e7\u00e3o.<\/p>\n\n\n\n<p>Quer ingressar na carreira p\u00fablica? <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/rj\/\">Confira os\u00a0concursos abertos no Rio de Janeiro!<\/a><\/p>\n\n\n\n<p><strong>Fiquem ligados na nossa p\u00e1gina para as pr\u00f3ximas not\u00edcias sobre o concurso TRT TJ!<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>O concurso TRT RJ tem edital autorizado para T\u00e9cnicos e Analistas Judici\u00e1rios, de n\u00edvel superior de escolaridade. O sal\u00e1rio no Tribunal Regional do Trabalho da 1\u00aa Regi\u00e3o poder\u00e1 chegar at\u00e9 R$15.387,88! Se interessa pelo certame? Fique e confira os demais detalhes sobre o edital autorizado para T\u00e9cnicos e Analistas Judici\u00e1rios do concurso TRT RJ! Quando [&hellip;]<\/p>\n","protected":false},"author":54687,"featured_media":243200,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-243192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/243192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54687"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=243192"}],"version-history":[{"count":8,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/243192\/revisions"}],"predecessor-version":[{"id":259977,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/243192\/revisions\/259977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/243200"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=243192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=243192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=243192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}