{"id":270952,"date":"2025-02-04T10:53:47","date_gmt":"2025-02-04T13:53:47","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=270952"},"modified":"2025-02-04T11:02:14","modified_gmt":"2025-02-04T14:02:14","slug":"concurso-pm-df-edital-publicado","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-pm-df-edital-publicado\/","title":{"rendered":"Concurso PM DF: Edital publicado com 147 vagas de oficiais!"},"content":{"rendered":"<p>O edital do <a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-pmdf-oficial\/\">concurso PM DF<\/a> foi divulgado! A Pol\u00edcia Militar do Distrito Federal anunciou a abertura do concurso para Oficial Combatente, oferecendo 147 vagas, das quais 49 s\u00e3o imediatas e 98 destinadas ao cadastro de reserva.<\/p>\n\n\n\n<p>O Cebraspe, banca organizadora, receber\u00e1 as inscri\u00e7\u00f5es de 24 de mar\u00e7o a 23 de abril de 2025. A taxa de inscri\u00e7\u00e3o \u00e9 de R$ 163,00, e os candidatos podem solicitar isen\u00e7\u00e3o at\u00e9 5 de mar\u00e7o. <\/p>\n\n\n\n<p>As avalia\u00e7\u00f5es objetivas e discursiva ser\u00e3o aplicadas no dia 1\u00ba de junho.<\/p>\n\n\n\n<p>N\u00e3o perca essa oportunidade! Fique atento aos prazos e comece j\u00e1 sua prepara\u00e7\u00e3o. Continue conosco e saiba todos os detalhes sobre o certame!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-prefeitura-de-suzano-inscries-\">Como realizar a inscri\u00e7\u00e3o para o concurso PM DF?<\/h2>\n\n\n\n<p>As inscri\u00e7\u00f5es do concurso PM DF ser\u00e3o realizadas exclusivamente pelo site da banca organizadora, o <a href=\"https:\/\/www.cebraspe.org.br\/\" target=\"_blank\" rel=\"noopener\">Cebraspe<\/a>, no per\u00edodo\u00a0<mark style=\"background-color:#8ed1fc\" class=\"has-inline-color\">das 10h do dia 24 de mar\u00e7o at\u00e9 \u00e0s 18h do dia 23 de abril de 2025.<\/mark><\/p>\n\n\n\n<p>Para se inscrever, o candidato dever\u00e1 acessar o site, selecionar o certame desejado e preencher o formul\u00e1rio de inscri\u00e7\u00e3o, informando corretamente seus dados pessoais, como CPF, RG e PIS\/PASEP.<\/p>\n\n\n\n<p>Ap\u00f3s esse processo, ser\u00e1 gerado um boleto banc\u00e1rio correspondente \u00e0 taxa de inscri\u00e7\u00e3o, que dever\u00e1 ser pago at\u00e9 a data de vencimento indicada.<\/p>\n\n\n\n<p>A taxa de inscri\u00e7\u00e3o \u00e9 no valor de R$ 163,00.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Isen\u00e7\u00e3o da Taxa de Inscri\u00e7\u00e3o<\/h3>\n\n\n\n<p>Candidatos que se enquadrarem nos seguintes crit\u00e9rios poder\u00e3o solicitar isen\u00e7\u00e3o da taxa de inscri\u00e7\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ser doador de sangue;<\/li>\n\n\n\n<li>Ser benefici\u00e1rio de programa social de complementa\u00e7\u00e3o ou suplementa\u00e7\u00e3o de renda institu\u00eddo pelo Governo do Distrito Federal;<\/li>\n\n\n\n<li>Declarar ser hipossuficientes, cuja renda familiar mensal per capita n\u00e3o exceda o valor de at\u00e9 1,5 sal\u00e1rio m\u00ednimo, e que tenham cursado o ensino m\u00e9dio completo em escola da rede p\u00fablica ou em institui\u00e7oes privadas na condi\u00e7\u00e3o de bolsista integral;<\/li>\n\n\n\n<li>presta\u00e7\u00e3o de servi\u00e7o \u00e0 Justi\u00e7a Eleitoral do Distrito Federal, na forma da Lei n\u00ba 5.818\/2017;<\/li>\n\n\n\n<li>candidato cadastrado no banco de dados como poss\u00edvel doador de medula \u00f3ssea;<\/li>\n\n\n\n<li>(benefici\u00e1rio de programas sociais do governo federal ou distrital, inscrito no Cad\u00danico<\/li>\n<\/ul><p>O pedido de isen\u00e7\u00e3o dever\u00e1 ser feito entre os dias <mark style=\"background-color:#8ed1fc\" class=\"has-inline-color\">24 de fevereiro e 5 de mar\u00e7o de 2025<\/mark>, anexando os documentos comprobat\u00f3rios na \u00e1rea do candidato no site da banca organizadora.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"concurso-pm-df-cargos-remunerao-e-benefcios\">Concurso PM DF: Cargos, remunera\u00e7\u00e3o e benef\u00edcios<\/h2>\n\n\n\n<p>De acordo com o <a href=\"https:\/\/cdn.cebraspe.org.br\/concursos\/PM_DF_25_CFO\/arquivos\/ED_1_PMDF_CFO_25_ABERTURA..PDF\" target=\"_blank\" rel=\"noopener\">edital<\/a>, o concurso PM DF oferece <strong>147 vagas<\/strong> para o cargo de <strong>Oficial Combatente<\/strong>, sendo <strong>49 para provimento imediato<\/strong> e <strong>98 destinadas ao cadastro de reserva<\/strong>.<\/p>\n\n\n\n<p>Para participar, os candidatos devem atender a crit\u00e9rios espec\u00edficos, incluindo:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>ter nacionalidade brasileira;<\/li>\n\n\n\n<li>estar quite com as obriga\u00e7\u00f5es do servi\u00e7o militar, em caso de candidato do sexo masculino;<\/li>\n\n\n\n<li><strong>ter conclu\u00eddo curso de n\u00edvel superior de gradua\u00e7\u00e3o em qualquer curso superior<\/strong>, comprovado por diploma, devidamente registrado, fornecido por institui\u00e7\u00e3o de ensino superior reconhecida pelo Minist\u00e9rio da Educa\u00e7\u00e3o (MEC), at\u00e9 a data de matr\u00edcula;<\/li>\n\n\n\n<li>ter, no <strong>m\u00ednimo, 18 anos<\/strong> at\u00e9 a data de matr\u00edcula;<\/li>\n\n\n\n<li>ter, no <strong>m\u00e1ximo, 30 anos at\u00e9 o \u00faltimo dia do per\u00edodo de inscri\u00e7\u00f5es<\/strong>, n\u00e3o se aplicando esse limite aos policiais militares da ativa da Corpora\u00e7\u00e3o;<\/li>\n\n\n\n<li>estar quite com as obriga\u00e7\u00f5es eleitorais;<\/li>\n\n\n\n<li>ter, descal\u00e7o e descoberto, a <strong>altura m\u00ednima de 1,65 m, para os candidatos do sexo masculino, e 1,60 m, para os candidatos do sexo feminino<\/strong>;<\/li>\n\n\n\n<li>n\u00e3o ser ex-aluno de estabelecimento de ensino militar, policial militar, policial civil, policial federal ou bombeiro militar, desligado por motivos disciplinares;<\/li>\n\n\n\n<li>n\u00e3o ter sido dispensado ou licenciado das For\u00e7as Armadas ou Auxiliares, por motivo considerado incompat\u00edvel com as exig\u00eancias para o CFO, nos termos deste edital.<\/li>\n<\/ul><p>Durante o Curso de Forma\u00e7\u00e3o de Oficiais, o Policial Militar ingressa como Aluno-Oficial PM, pertencendo ao Quadro de Pra\u00e7as Especiais. Durante os tr\u00eas anos de forma\u00e7\u00e3o, a remunera\u00e7\u00e3o inicial do Cadete do 1\u00ba ano ser\u00e1 de <strong>R$ 8.007,76<\/strong>.<\/p>\n\n\n\n<p>Ap\u00f3s a conclus\u00e3o do curso e aprova\u00e7\u00e3o, o militar ser\u00e1 declarado Aspirante-a-Oficial, fase em que permanecer\u00e1 durante o est\u00e1gio probat\u00f3rio, recebendo uma remunera\u00e7\u00e3o de <strong>R$ 14.451,93<\/strong>.<\/p>\n\n\n\n<p>Ao t\u00e9rmino do est\u00e1gio, ser\u00e1 promovido ao posto de 2\u00ba Tenente do Quadro de Oficiais Policiais Militares, passando a receber <strong>R$ 17.034,85<\/strong>.<\/p>\n\n\n\n<p>Al\u00e9m da remunera\u00e7\u00e3o, o aprovado tamb\u00e9m ter\u00e1 direito ao aux\u00edlio-alimenta\u00e7\u00e3o no valor de R$ 850,00, somado ao sal\u00e1rio.<\/p>\n\n\n\n<div class=\"nova-continue-reading\"><strong>Adquira j\u00e1:<\/strong> <a href=\"https:\/\/www.novaconcursos.com.br\/curso-online\/curso-pm-df-curso-formacao-oficiais-cfo\">Curso PM-DF Curso de Forma\u00e7\u00e3o de Oficiais<\/a> (CFO)<\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quais-sero-as-etapas-das-provas\">Quais ser\u00e3o as etapas das provas?<\/h2>\n\n\n\n<p>O concurso PM DF, sob organiza\u00e7\u00e3o do Cabraspe, contar\u00e1 com a seguinte estrutura:<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-04-as-09.35.46_3b66e11d.webp\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"380\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-04-as-09.35.46_3b66e11d-1024x380.webp\" alt=\"Estrututra avaliativa do concurso PM DF\n\" class=\"wp-image-270961\" title=\"\" srcset=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-04-as-09.35.46_3b66e11d-300x111.webp 300w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-04-as-09.35.46_3b66e11d-480x178.webp 480w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-04-as-09.35.46_3b66e11d-768x285.webp 768w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-04-as-09.35.46_3b66e11d-1024x380.webp 1024w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2025\/02\/Imagem-do-WhatsApp-de-2025-02-04-as-09.35.46_3b66e11d.webp 1080w\" sizes=\"auto, (max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1200px) 70vw, 768px\"><\/a><figcaption><\/figcaption><\/figure><p><\/p>\n\n\n\n<p>A <strong>prova objetiva<\/strong>, de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio, ser\u00e1 do tipo m\u00faltipla escolha e abordar\u00e1 as seguintes disciplinas:<\/p>\n\n\n\n<p><strong>Conhecimentos b\u00e1sicos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>L\u00edngua Portuguesa;<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o;<\/li>\n\n\n\n<li>DF e Pol\u00edcia para Mulheres;<\/li>\n\n\n\n<li>Direitos Humanos;<\/li>\n\n\n\n<li>No\u00e7\u00f5es de Criminologia;<\/li>\n\n\n\n<li>Racioc\u00ednio L\u00f3gico;<\/li>\n\n\n\n<li>L\u00edngua Inglesa.<\/li>\n<\/ul><p><strong>Conhecimentos espec\u00edficos <\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Administra\u00e7\u00e3o;<\/li>\n\n\n\n<li>Direito Constitucional;<\/li>\n\n\n\n<li>Direito Administrativo;<\/li>\n\n\n\n<li>Direito Penal;<\/li>\n\n\n\n<li>Direito Processual Penal;<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o Penal e Processual Penal Extravagante;<\/li>\n\n\n\n<li>Direito Penal Militar;<\/li>\n\n\n\n<li>Direito Processual Penal Militar.<\/li>\n<\/ul><p>A <strong>prova discursiva<\/strong> ter\u00e1 valor m\u00e1ximo de 20 pontos e consistir\u00e1 na resposta a uma quest\u00e3o discursiva de at\u00e9 30 linhas, abordando temas relacionados aos conhecimentos espec\u00edficos.<\/p>\n\n\n\n<p>Cada prova discursiva ser\u00e1 avaliada em dois crit\u00e9rios:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Conte\u00fado, considerando a pertin\u00eancia e profundidade da resposta.<\/li>\n\n\n\n<li>Dom\u00ednio da modalidade escrita da L\u00edngua Portuguesa, analisando coes\u00e3o, coer\u00eancia e corre\u00e7\u00e3o gramatical.<\/li>\n<\/ul><p>A nota final nas provas objetivas ser\u00e1 calculada a partir da soma das notas obtidas na avalia\u00e7\u00e3o objetiva e na avalia\u00e7\u00e3o discursiva.<\/p>\n\n\n\n<p>Para o <strong>teste de aptid\u00e3o f\u00edsica<\/strong> (TAF) ser\u00e1 convocados aqueles candidatos que foram aprovados nas etapas anteriores e consistir\u00e1 na execu\u00e7\u00e3o de flex\u00e3o em barra fixa (para os candidatos do sexo masculino) ou de barra est\u00e1tica (candidatas do sexo feminino), flex\u00e3o abdominal remador, nata\u00e7\u00e3o e corrida de 12 minutos.<\/p>\n\n\n\n<p>Todas as etapas do concurso PM DF ser\u00e3o realizadas no Distrito Federal.<\/p>\n\n\n\n<div class=\"nova-continue-reading\"><strong>Leia tamb\u00e9m:\u00a0<\/strong><a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos-abertos\/\">Concursos abertos a n\u00edvel nacional!<\/a><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"CONCURSO CFO PMDF - EDITAL PUBLICADO COM 147 VAGAS E INICIAIS DE R$ 17 MIL \ud83c\udfaf\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/gvZXi3Jy-k0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>O edital do concurso PM DF foi divulgado! Ser\u00e3o ofertadas 147 vagas para o cargo de Oficial Combatente. As provas ser\u00e3o aplicadas no dia 1\u00ba de junho. Fiquem atentos aos prazos!<\/p>\n","protected":false},"author":54695,"featured_media":270953,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228,44983,44943,44941],"tags":[18639,45030],"class_list":["post-270952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-df","category-carreira-militar","category-carreira-policial","tag-concurso-pm-df","tag-concursos-abertos-df-2"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/270952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54695"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=270952"}],"version-history":[{"count":4,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/270952\/revisions"}],"predecessor-version":[{"id":270974,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/270952\/revisions\/270974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/270953"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=270952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=270952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=270952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}