{"id":44568,"date":"2025-02-25T13:06:05","date_gmt":"2025-02-25T16:06:05","guid":{"rendered":"http:\/\/www.novaconcursos.com.br\/portal\/?post_type=nc-public-tender&#038;p=44568"},"modified":"2025-02-25T13:09:28","modified_gmt":"2025-02-25T16:09:28","slug":"concurso-ufsb","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-ufsb\/","title":{"rendered":"Concurso UFSB: Edital publicado. 71 vagas e sal\u00e1rios de R$5 mil!"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Aten\u00e7\u00e3o, concurseiros! O <strong>concurso UFSB<\/strong> (Universidade Federal do Sul da Bahia) teve seu <strong>edital publicado<\/strong> e oferece <strong>71 vagas<\/strong> para a \u00e1rea t\u00e9cnica-administrativa. S\u00e3o oportunidades em diversas especialidades, com exig\u00eancia de <mark style=\"background-color:#8ed1fc\" class=\"has-inline-color\">n\u00edveis m\u00e9dio e superior<\/mark>.<\/p>\n\n\n\n    <div class=\"nova-resumo-edital\">\n        <h2 class=\"nova-resumo-edital-title\" id=\"resumo-edital\">Resumo Edital<\/h2>\n        <ul class=\"nova-resumo-edital-list nova-menu\"><li>\n                <img decoding=\"async\" width=\"24\" height=\"24\" loading=\"lazy\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/themes\/nova-theme\/includes\/assets\/img\/person.svg\" aria-hidden=\"true\" alt=\"\u00edcone pessoa\" title=\"\"><span>\n                    <b>Vagas: <\/b> 71\n                <\/span>\n            <\/li>\n            <li>\n                <img decoding=\"async\" width=\"24\" height=\"24\" loading=\"lazy\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/themes\/nova-theme\/includes\/assets\/img\/inscricoes.svg\" aria-hidden=\"true\" alt=\"\u00edcone pessoa\" title=\"\"><span>\n                    <b>Per\u00edodo de inscri\u00e7\u00f5es: <\/b> 25\/02\/2025 a 24\/03\/2025\n                <\/span>\n            <\/li>\n            <li>\n                <img decoding=\"async\" width=\"24\" height=\"24\" loading=\"lazy\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/themes\/nova-theme\/includes\/assets\/img\/taxa-inscricao.svg\" aria-hidden=\"true\" alt=\"\u00edcone pessoa\" title=\"\"><span>\n                    <b>Taxa de inscri\u00e7\u00e3o: <\/b> R$ 120,00 a R$ 150,00\n                <\/span>\n            <\/li>\n            <li>\n                <img decoding=\"async\" width=\"24\" height=\"24\" loading=\"lazy\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/themes\/nova-theme\/includes\/assets\/img\/prova.svg\" aria-hidden=\"true\" alt=\"\u00edcone pessoa\" title=\"\"><span>\n                    <b>Prova: <\/b> 18\/05\/2025\n                <\/span>\n            <\/li>\n            <li>\n                <img decoding=\"async\" width=\"24\" height=\"24\" loading=\"lazy\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/themes\/nova-theme\/includes\/assets\/img\/banca.svg\" aria-hidden=\"true\" alt=\"\u00edcone pessoa\" title=\"\"><span>\n                    <b>Banca: <\/b> IDECAN\n                <\/span>\n            <\/li>\n        <\/ul><div class=\"nova-resumo-edital-baixar\">\n            <a href=\"https:\/\/www.in.gov.br\/en\/web\/dou\/-\/edital-n-1-de-24-de-fevereiro-de-2025-614817954\" target=\"_blank\" rel=\"noopener\">\n                Baixe aqui o edital\n            <\/a>\n        <\/div>\n    <\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Com sal\u00e1rios de at\u00e9 R$ 5 mil, al\u00e9m de benef\u00edcios, essa \u00e9 a chance de garantir um bom emprego na \u00e1rea p\u00fablica e conquistar estabilidade profissional. N\u00e3o perca tempo e fique por dentro de todos os detalhes dessa sele\u00e7\u00e3o!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"como-fazer-a-inscrio-no-concurso-ufsb\">Como fazer a inscri\u00e7\u00e3o no concurso UFSB?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O concurso UFSB (Universidade Federal do Sul da Bahia) est\u00e1 com <strong>inscri\u00e7\u00f5es abertas <\/strong>e voc\u00ea pode garantir a sua participa\u00e7\u00e3o <strong>at\u00e9 24 de mar\u00e7o de 2025<\/strong>. Para se inscrever, basta acessar o portal da banca organizadora, o <a href=\"https:\/\/www.idecan.org.br\/\" data-type=\"link\" data-id=\"https:\/\/www.idecan.org.br\/\" target=\"_blank\" rel=\"noopener\">Instituto IDECAN<\/a>. Fique atento ao prazo e aproveite a chance de participar da sele\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A taxa de inscri\u00e7\u00e3o varia conforme o n\u00edvel de escolaridade exigido para os cargos, com os seguintes valores:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>N\u00edvel M\u00e9dio: R$ 120,00<\/li>\n\n\n\n<li>N\u00edvel Superior: R$ 150,00<\/li>\n<\/ul><p class=\"wp-block-paragraph\">Caso se encaixe nas condi\u00e7\u00f5es para isen\u00e7\u00e3o da taxa, a solicita\u00e7\u00e3o pode ser feita para candidatos que atendam aos seguintes requisitos:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Inscritos no Cadastro \u00danico (Cad\u00danico)<\/li>\n\n\n\n<li>Doador de Medula \u00d3ssea<\/li>\n<\/ul><p class=\"wp-block-paragraph\">Aproveite para se organizar e n\u00e3o deixar passar essa oportunidade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"cargos-e-vagas-do-concurso-ufsb\">Cargos e vagas do concurso UFSB<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O concurso UFSB \u00e9 uma excelente oportunidade para quem busca estabilidade e crescimento profissional no setor p\u00fablico. O edital oferece <strong>71 vagas<\/strong> distribu\u00eddas entre os <mark style=\"background-color:#8ed1fc\" class=\"has-inline-color\">n\u00edveis m\u00e9dio, t\u00e9cnico e superior<\/mark>, com v\u00e1rias op\u00e7\u00f5es para diferentes \u00e1reas. Confira como as vagas est\u00e3o organizadas:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">N\u00edvel M\u00e9dio\/T\u00e9cnico<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Assistente em Administra\u00e7\u00e3o: 21 vagas<\/li>\n\n\n\n<li>T\u00e9cnico de Laborat\u00f3rio \u2013 An\u00e1lises Cl\u00ednicas: 1 vaga<\/li>\n\n\n\n<li>T\u00e9cnico de Laborat\u00f3rio \u2013 Qu\u00edmica: 2 vagas<\/li>\n\n\n\n<li>T\u00e9cnico em Enfermagem: 1 vaga<\/li>\n\n\n\n<li>T\u00e9cnico de Tecnologia da Informa\u00e7\u00e3o: 2 vagas<\/li>\n<\/ul><h3 class=\"wp-block-heading\">N\u00edvel Superior<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Administrador: 20 vagas<\/li>\n\n\n\n<li>Analista de Tecnologia da Informa\u00e7\u00e3o: 3 vagas<\/li>\n\n\n\n<li>Arque\u00f3logo: 2 vagas<\/li>\n\n\n\n<li>Assistente Social: 1 vaga<\/li>\n\n\n\n<li>Bibliotec\u00e1rio \u2013 Documentalista: 1 vaga<\/li>\n\n\n\n<li>Bi\u00f3logo: 1 vaga<\/li>\n\n\n\n<li>Enfermeiro: 4 vagas<\/li>\n\n\n\n<li>Engenheiro Civil: 1 vaga<\/li>\n\n\n\n<li>Engenheiro de Seguran\u00e7a no Trabalho: 1 vaga<\/li>\n\n\n\n<li>M\u00e9dico\/Psiquiatra: 1 vaga<\/li>\n\n\n\n<li>Nutricionista: 3 vagas<\/li>\n\n\n\n<li>Pedagogo: 4 vagas<\/li>\n\n\n\n<li>Psic\u00f3logo: 2 vagas<\/li>\n<\/ul><p class=\"wp-block-paragraph\">Se voc\u00ea tem interesse em ingressar na UFSB e quer aproveitar uma chance de trabalhar em uma institui\u00e7\u00e3o renomada, esse concurso pode ser a oportunidade perfeita para voc\u00ea.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quanto-ganha-um-concursado-da-ufsb\">Quanto ganha um concursado da UFSB?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O concurso UFSB conta com sal\u00e1rios atrativos e benef\u00edcios importantes. Se voc\u00ea busca uma carreira est\u00e1vel, vale a pena conferir essa chance!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A remunera\u00e7\u00e3o varia conforme o n\u00edvel de escolaridade:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>N\u00edvel m\u00e9dio\/t\u00e9cnico: <strong>R$ 4.029,90<\/strong><\/li>\n\n\n\n<li>N\u00edvel superior: <strong>R$ 5.967,04<\/strong><\/li>\n<\/ul><p class=\"wp-block-paragraph\">Al\u00e9m dos sal\u00e1rios, o concurso oferece um aux\u00edlio alimenta\u00e7\u00e3o de <strong>R$ 1.000,00<\/strong>. A jornada de trabalho \u00e9 de 40 horas semanais, o que garante um bom equil\u00edbrio entre a vida profissional e pessoal. Esta \u00e9 uma excelente chance para quem quer se estabelecer na carreira p\u00fablica com \u00f3timas condi\u00e7\u00f5es!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"atribuies-da-ufsb\">Atribui\u00e7\u00f5es da UFSB<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Confira a seguir, algumas atribui\u00e7\u00f5es dos cargos com maior oferta de vagas do certame:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">N\u00edvel m\u00e9dio\/t\u00e9cnico<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Assistente em Administra\u00e7\u00e3o<\/strong><br>O Assistente em Administra\u00e7\u00e3o tem um papel essencial nas \u00e1reas de recursos humanos, administra\u00e7\u00e3o, finan\u00e7as e log\u00edstica. Ele auxilia no atendimento a usu\u00e1rios, no tratamento de documentos diversos, al\u00e9m de preparar relat\u00f3rios e planilhas. Entre outras atividades, ele tamb\u00e9m apoia na execu\u00e7\u00e3o de servi\u00e7os gerais de escrit\u00f3rio e nas tarefas de ensino, pesquisa e extens\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>T\u00e9cnico de Tecnologia da Informa\u00e7\u00e3o<\/strong><br>Esse cargo abrange desde o desenvolvimento de sistemas e aplica\u00e7\u00f5es at\u00e9 a manuten\u00e7\u00e3o de bancos de dados e codifica\u00e7\u00e3o de programas. O T\u00e9cnico de TI tamb\u00e9m \u00e9 respons\u00e1vel por selecionar as ferramentas adequadas para o desenvolvimento de sistemas e prestar suporte t\u00e9cnico aos usu\u00e1rios.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">N\u00edvel superior<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Administrador<\/strong><br>O Administrador \u00e9 o respons\u00e1vel pelo planejamento e organiza\u00e7\u00e3o nas \u00e1reas de recursos humanos, finan\u00e7as e materiais. Ele tamb\u00e9m elabora projetos e promove estudos para o controle organizacional, prestando consultoria administrativa e assessorando em projetos estrat\u00e9gicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Analista de Tecnologia da Informa\u00e7\u00e3o<\/strong><br>Este cargo exige o desenvolvimento e a implanta\u00e7\u00e3o de sistemas informatizados, com foco em especifica\u00e7\u00e3o de programas e codifica\u00e7\u00e3o de aplicativos. O analista tamb\u00e9m realiza a administra\u00e7\u00e3o de ambientes informatizados e oferece suporte t\u00e9cnico aos usu\u00e1rios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"etapas-e-provas-da-ufsb\">Etapas e provas da UFSB<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea est\u00e1 de olho no concurso da USFB, \u00e9 importante se preparar com foco nas etapas definidas no edital. O concurso ocorrer\u00e1 em uma \u00fanica etapa, com a <strong>Prova Objetiva<\/strong>, de <strong>car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As provas ocorrer\u00e3o em dois turnos no dia <mark style=\"background-color:#8ed1fc\" class=\"has-inline-color\">18 de maio de 2025.<\/mark> Para os candidatos de n\u00edvel superior, as provas ser\u00e3o realizadas no turno da manh\u00e3. J\u00e1 os candidatos de n\u00edvel m\u00e9dio far\u00e3o a prova no turno da tarde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A prova ser\u00e1 aplicada em v\u00e1rias cidades da Bahia, como Barra, Barreiras, Bom Jesus da Lapa, Itabuna, Ponto Seguro, Salvador e Teixeira de Freitas. A seguir, vamos entender melhor o que esperar de cada parte da prova!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Prova Objetiva<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A Prova Objetiva ser\u00e1 composta por um total de 65 quest\u00f5es, distribu\u00eddas entre Conhecimentos Comuns e Conhecimentos Espec\u00edficos do Cargo, com a seguinte estrutura:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Conhecimentos Comuns (40 quest\u00f5es):\n<ul class=\"wp-block-list\"><li>L\u00edngua Portuguesa: 10 quest\u00f5es<\/li>\n\n\n\n<li>Racioc\u00ednio L\u00f3gico Matem\u00e1tico: 5 quest\u00f5es<\/li>\n\n\n\n<li>Inform\u00e1tica: 5 quest\u00f5es<\/li>\n\n\n\n<li>Legisla\u00e7\u00e3o: 20 quest\u00f5es<\/li>\n<\/ul><\/li>\n\n\n\n<li>Conhecimentos Espec\u00edficos do Cargo (25 quest\u00f5es)<\/li>\n<\/ul><p class=\"wp-block-paragraph\">Cada quest\u00e3o ter\u00e1 5 alternativas e apenas uma resposta correta. Essa prova ser\u00e1 decisiva para a classifica\u00e7\u00e3o, pois ela tem car\u00e1ter tanto eliminat\u00f3rio quanto classificat\u00f3rio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O concurso da USFB ter\u00e1 validade de 2 anos, com possibilidade de prorroga\u00e7\u00e3o por mais 2 anos, caso haja necessidade de preenchimento de vagas durante esse per\u00edodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea est\u00e1 se preparando para esse concurso, \u00e9 essencial focar na estrutura da prova, pois todas as quest\u00f5es ter\u00e3o um impacto direto na sua aprova\u00e7\u00e3o. Boa sorte na sua prepara\u00e7\u00e3o!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"materiais-preparatrios\">Materiais preparat\u00f3rios<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para conquistar a aprova\u00e7\u00e3o no concurso UFSB, \u00e9 essencial contar com materiais de estudo eficazes e uma rotina disciplinada de prepara\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Na <a href=\"https:\/\/www.novaconcursos.com.br\/\" data-type=\"link\" data-id=\"https:\/\/www.novaconcursos.com.br\/\">Nova Concursos<\/a>, voc\u00ea encontra a melhor base para alcan\u00e7ar seus objetivos, com mais de <strong>70 mil aprovados<\/strong> em todo o Brasil! Nossa metodologia combina qualidade e conte\u00fado completo, projetado para tornar sua prepara\u00e7\u00e3o mais eficiente e direcionada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saiba quais s\u00e3o os materiais que v\u00e3o impulsionar seus estudos e d\u00ea o pr\u00f3ximo passo rumo \u00e0 sua vaga no concurso UFSB, garantindo a estabilidade e o crescimento profissional que voc\u00ea merece!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Apostila B\u00e1sico para Concursos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A <a href=\"https:\/\/www.novaconcursos.com.br\/apostila\/basico-concurso?srsltid=AfmBOopqN09QHdt4LNe7lk-bntbmmTY1WXhK5n0Zqc3hiEkLMvWuvbdb\" data-type=\"link\" data-id=\"https:\/\/www.novaconcursos.com.br\/apostila\/basico-concurso?srsltid=AfmBOopqN09QHdt4LNe7lk-bntbmmTY1WXhK5n0Zqc3hiEkLMvWuvbdb\">Apostila B\u00e1sico para Concursos<\/a> \u00e9 a base que voc\u00ea precisa para iniciar sua prepara\u00e7\u00e3o para o concurso UFSB!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esse material aborda de maneira pr\u00e1tica e objetiva os conte\u00fados essenciais, reunindo quest\u00f5es recentes das principais bancas organizadoras do pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ideal para quem est\u00e1 come\u00e7ando ou precisa organizar seus estudos, a apostila oferece uma prepara\u00e7\u00e3o direta e focada no que realmente importa, ajudando voc\u00ea a dar os primeiros passos rumo \u00e0 aprova\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comece hoje mesmo a se preparar e esteja um passo mais perto da sua vaga!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L\u00edngua Portuguesa para Concursos<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O livro <a href=\"https:\/\/www.novaconcursos.com.br\/apostila\/lingua-portuguesa-concursos?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=google-gs-apostila-impressa-padrao&amp;gad_source=1&amp;gclid=Cj0KCQiA7se8BhCAARIsAKnF3rwak9OVKwCZPyHPgjqYqoBO8QxrKlI6fagFGeay1fWQnOGZcJBOKoQaApDlEALw_wcB\" data-type=\"link\" data-id=\"https:\/\/www.novaconcursos.com.br\/apostila\/lingua-portuguesa-concursos?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=google-gs-apostila-impressa-padrao&amp;gad_source=1&amp;gclid=Cj0KCQiA7se8BhCAARIsAKnF3rwak9OVKwCZPyHPgjqYqoBO8QxrKlI6fagFGeay1fWQnOGZcJBOKoQaApDlEALw_wcB\">L\u00edngua Portuguesa para Concursos<\/a> \u00e9 o parceiro ideal para sua prepara\u00e7\u00e3o rumo \u00e0 aprova\u00e7\u00e3o no concurso UFSB!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com um roteiro de estudos personalizado, o material direciona seu aprendizado de forma eficiente, permitindo que voc\u00ea se concentre nos temas mais relevantes e aumente suas chances de sucesso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O livro apresenta uma an\u00e1lise detalhada dos assuntos mais cobrados, al\u00e9m de in\u00fameras quest\u00f5es comentadas de provas anteriores, que ajudam voc\u00ea a dominar os t\u00f3picos na teoria e na pr\u00e1tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo o conte\u00fado foi pensado para ser visualmente estimulante e organizado de forma clara, proporcionando uma experi\u00eancia de aprendizado confort\u00e1vel e envolvente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adquira agora o material e fique mais perto da sua aprova\u00e7\u00e3o!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Curso Online Guia da Aprova\u00e7\u00e3o<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O caminho at\u00e9 a aprova\u00e7\u00e3o em concursos p\u00fablicos \u00e9 desafiador, e uma das maiores dificuldades enfrentadas pelos concurseiros \u00e9 saber como planejar os estudos de maneira eficiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pensando nisso, desenvolvemos o Curso Guia da Aprova\u00e7\u00e3o, com o Prof. Guilherme Volts. No curso, voc\u00ea encontrar\u00e1 ferramentas essenciais para criar seu planejamento de estudos, estrat\u00e9gias para melhorar seu desempenho, t\u00e9cnicas de revis\u00e3o, exerc\u00edcios pr\u00e1ticos e avalia\u00e7\u00f5es. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Garanta a orienta\u00e7\u00e3o que voc\u00ea precisa para transformar sua prepara\u00e7\u00e3o e conquistar sua t\u00e3o sonhada vaga na carreira p\u00fablica!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p><div class=\"nova-continue-reading\"> Adquira j\u00e1: <a href=\"https:\/\/www.novaconcursos.com.br\/curso-online\/guia-aprovacao\" data-type=\"link\" data-id=\"https:\/\/www.novaconcursos.com.br\/curso-online\/guia-aprovacao\">Curso Online Guia da Aprova\u00e7\u00e3o<\/a><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"quando-foi-o-ltimo-concurso-usfb\">Quando foi o \u00faltimo concurso USFB?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O \u00faltimo concurso UFSB ocorreu em 2023, com vagas para cargos de Professor do Magist\u00e9rio Superior. Os sal\u00e1rios iniciais oferecidos foram de R$ 11.000,00.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O concurso contou com as seguintes etapas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Prova escrita e did\u00e1tica (de car\u00e1ter eliminat\u00f3rio e classificat\u00f3rio)<\/li>\n\n\n\n<li>Prova de t\u00edtulos (de car\u00e1ter classificat\u00f3rio)<\/li>\n<\/ul><h2 class=\"wp-block-heading\" id=\"sobre-a-usfb\">Sobre a USFB<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A <a href=\"https:\/\/ufsb.edu.br\/\" data-type=\"link\" data-id=\"https:\/\/ufsb.edu.br\/\" target=\"_blank\" rel=\"noopener\">Universidade Federal do Sul da Bahia (UFSB)<\/a> \u00e9 uma institui\u00e7\u00e3o de ensino superior federal, criada pela Lei n\u00ba 12.818, em 5 de junho de 2013. Localizada nas regi\u00f5es Sul e Extremo Sul da Bahia, a UFSB se destaca pela qualidade de ensino e pelo compromisso com a forma\u00e7\u00e3o de bons profissionais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reconhecida por sua atua\u00e7\u00e3o em diversas \u00e1reas, a universidade contribui para o desenvolvimento da regi\u00e3o, oferecendo cursos e programas voltados para a educa\u00e7\u00e3o, a pesquisa e a extens\u00e3o. A UFSB \u00e9 uma refer\u00eancia no estado, atraindo estudantes e professores que buscam uma forma\u00e7\u00e3o s\u00f3lida e de excel\u00eancia.<\/p>","protected":false},"excerpt":{"rendered":"<p>O edital do concurso UFSB foi publicado1 A oferta \u00e9 de 71 vagas para a \u00e1rea t\u00e9cnica-administrativa, de n\u00edveis m\u00e9dio e superior, com sal\u00e1rios de at\u00e9 R$ 5 mil. Confira os detalhes!<\/p>\n","protected":false},"author":54693,"featured_media":273165,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[44999,44951,44939],"tags":[18346,45025],"class_list":["post-44568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concursos","category-ba","category-carreira-administrativa","tag-concurso-ufsb","tag-concursos-abertos-ba"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/44568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/54693"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=44568"}],"version-history":[{"count":3,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/44568\/revisions"}],"predecessor-version":[{"id":273173,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/44568\/revisions\/273173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/273165"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=44568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=44568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=44568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}