{"id":63591,"date":"2018-02-27T16:58:22","date_gmt":"2018-02-27T19:58:22","guid":{"rendered":"http:\/\/www.novaconcursos.com.br\/portal\/?p=63591"},"modified":"2021-01-28T15:40:45","modified_gmt":"2021-01-28T18:40:45","slug":"concurso-diplomata-cacd-edital-com-30-vagas-ainda-no-primeiro-semestre-2018-02","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-diplomata-cacd-edital-com-30-vagas-ainda-no-primeiro-semestre-2018-02\/","title":{"rendered":"Concurso Diplomata (CACD): Edital com 30 vagas ainda no primeiro semestre!"},"content":{"rendered":"<p>Excelente not\u00edcia aos concurseiros que almejam seguir <strong>carreira de Diplomata<\/strong>! O Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores (<strong>MRE<\/strong>) anunciou a realiza\u00e7\u00e3o de um novo <strong>Concurso de Admiss\u00e3o \u00e0 Carreira de Diplomata (CACD)<\/strong>!<\/p>\n<p>De acordo com a assessoria de imprensa do \u00f3rg\u00e3o, a ideia \u00e9 publicar o <strong>edital Diplomata<\/strong> em breve, com imediata abertura das inscri\u00e7\u00f5es.<\/p>\n<p>O certame ter\u00e1 oferta de <strong>30 vagas imediatas<\/strong> para candidatos de <strong>n\u00edvel superior<\/strong> com sal\u00e1rios de at\u00e9 <strong>R$ 17,3 mil!<\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Previs\u00e3o do edital<\/strong><\/span><\/p>\n<p>O \u00f3rg\u00e3o tem tradi\u00e7\u00e3o de realizar concurso p\u00fablico at\u00e9 o <strong>final do primeiro semestre<\/strong> de cada ano. O que significa que o novo edital dever\u00e1 <span style=\"color: #000000;\">ser<\/span> publicado at\u00e9<strong> julho de 2018<\/strong>.<\/p>\n<p>Se voc\u00ea planeja alcan\u00e7ar a aprova\u00e7\u00e3o e garantir uma das vagas, \u00e9 melhor <strong>dar in\u00edcio aos estudos imediatamente!<\/strong><\/p>\n<p><span style=\"color: #000000;\"><strong>Vagas e sal\u00e1rios<\/strong><\/span><\/p>\n<p>Est\u00e3o previstas <strong>30 vagas<\/strong> para a <strong>Carreira de Diplomata do Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores<\/strong>, cargo que exige <strong>ensino superior completo<\/strong>, n\u00e3o necessitando de gradua\u00e7\u00e3o espec\u00edfica.<\/p>\n<p>Os aprovados no concurso ingressar\u00e3o na carreira como <strong>Terceiros-Secret\u00e1rios<\/strong> do MRE e far\u00e3o jus \u00e0 remunera\u00e7\u00e3o <strong>R$ 17.393,40<\/strong>, incluindo <strong>R$ 458,00<\/strong> de aux\u00edlio-alimenta\u00e7\u00e3o.<\/p>\n<p><strong>Como ser\u00e1 a Prova?<\/strong><\/p>\n<p>A expectativa \u00e9 de a avalia\u00e7\u00e3o ser\u00e1 dividida em <strong>tr\u00eas fases<\/strong>. Na primeira, os concorrentes passar\u00e3o por <strong>prova objetiva<\/strong>, composta por 73 quest\u00f5es de L\u00edngua Portuguesa, Hist\u00f3ria do Brasil, Hist\u00f3ria Mundial, Geografia, Pol\u00edtica Internacional, L\u00edngua Inglesa, No\u00e7\u00f5es de Economia e No\u00e7\u00f5es de Direito e Direito Internacional P\u00fablico. A prova objetiva ser\u00e1 aplicada nas capitais dos 26 Estados da Federa\u00e7\u00e3o e no Distrito Federal.<\/p>\n<p>Na segunda fase, h\u00e1 uma <strong>prova discursiva<\/strong> de Portugu\u00eas (reda\u00e7\u00e3o e dois exerc\u00edcios).<\/p>\n<p>J\u00e1 na terceira e \u00faltima fase, s\u00e3o <strong>seis avalia\u00e7\u00f5es<\/strong>, sendo cinco delas discursivas sobre Hist\u00f3ria do Brasil; Geografia e Pol\u00edtica Internacional; L\u00edngua Inglesa; No\u00e7\u00f5es de Economia; No\u00e7\u00f5es de Direito e Direito Internacional P\u00fablico; O sexto exame \u00e9 objetivo sobre Espanhol e Franc\u00eas.<\/p>\n<p>Os selecionados nas etapas anteriores realizam ainda um<strong> curso de forma\u00e7\u00e3o<\/strong> no Instituto Rio Branco, em Bras\u00edlia.<\/p>\n<p>A\u00a0<span style=\"text-decoration: underline; color: #0000ff;\"><strong><a style=\"color: #0000ff; text-decoration: underline;\" href=\"https:\/\/www.novaconcursos.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Nova Concursos<\/a><\/strong><\/span>\u00a0tem ajudado h\u00e1 mais de 8 anos quem quer vencer a batalha do concurso p\u00fablico. Se voc\u00ea quer aumentar suas chances de passar, conhe\u00e7a nossos materiais acessando nosso site!<\/p>","protected":false},"excerpt":{"rendered":"<p>Excelente not\u00edcia aos concurseiros que almejam seguir carreira de Diplomata! O Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores (MRE) anunciou a realiza\u00e7\u00e3o de um novo Concurso de Admiss\u00e3o \u00e0 Carreira de Diplomata (CACD)! De acordo com a assessoria de imprensa do \u00f3rg\u00e3o, a ideia \u00e9 publicar o edital Diplomata em breve, com imediata abertura das inscri\u00e7\u00f5es. O certame [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[25208,25206,25207,25209],"class_list":["post-63591","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-concurso-carreira-de-diplomata-do-ministerio-das-relacoes-exteriores","tag-concurso-de-admissao-a-carreira-de-diplomata","tag-concurso-diplomata-cacd-2018","tag-concurso-diplomata-2018"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/63591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=63591"}],"version-history":[{"count":3,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/63591\/revisions"}],"predecessor-version":[{"id":113796,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/63591\/revisions\/113796"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=63591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=63591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=63591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}