{"id":92119,"date":"2019-09-25T12:08:56","date_gmt":"2019-09-25T15:08:56","guid":{"rendered":"https:\/\/www.novaconcursos.com.br\/portal\/?p=92119"},"modified":"2019-09-25T12:08:59","modified_gmt":"2019-09-25T15:08:59","slug":"concurso-tcu-certame-devera-ser-autorizado-apos-aprovacao-orcamentaria","status":"publish","type":"post","link":"https:\/\/www.novaconcursos.com.br\/portal\/noticias\/concurso-tcu-certame-devera-ser-autorizado-apos-aprovacao-orcamentaria\/","title":{"rendered":"Concurso TCU: Certame dever\u00e1 ser autorizado ap\u00f3s aprova\u00e7\u00e3o or\u00e7ament\u00e1ria!"},"content":{"rendered":"<p>O <a href=\"https:\/\/www.novaconcursos.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Concurso (abre numa nova aba)\">Concurso<\/a> TCU (Tribunal de Contas da Uni\u00e3o), dever\u00e1 ser <strong>autorizado pelo Congresso Nacional<\/strong> ap\u00f3s a <strong>aprova\u00e7\u00e3o da Lei de Diretrizes Or\u00e7ament\u00e1rias <\/strong>(LDO). H\u00e1 uma previs\u00e3o que seja ofertada <strong>30 vagas em 2020.<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.novaconcursos.com.br\/portal\/concursos\/concurso-tcu\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"\u21d2 Confira todas as informa\u00e7\u00f5es na p\u00e1gina do concurso! (abre numa nova aba)\">\u21d2 Confira todas as informa\u00e7\u00f5es na p\u00e1gina do concurso!<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"situao-atual-do-concurso-tcu\">Situa\u00e7\u00e3o atual do\nconcurso TCU<\/h2>\n\n\n\n<p>De acordo com a <strong>Assessoria de Imprensa<\/strong> do Senado Federal, para qualquer <strong>despensa da Uni\u00e3o<\/strong>, deve ser realizado antes uma <strong>previs\u00e3o or\u00e7ament\u00e1ria<\/strong> que \u00e9 constitu\u00edda por <strong>duas etapas<\/strong>: a Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) e, em seguida, a Lei Or\u00e7ament\u00e1rio Anual (LOA).<\/p>\n\n\n\n<p>Atualmente, o Congresso Nacional est\u00e1 <strong>analisando o Projeto de Lei de Diretrizes Or\u00e7ament\u00e1rias <\/strong>(LDO) para 2020. S\u00f3 depois do<strong> aval<\/strong> do documento e que ser\u00e1<strong> encaminhado<\/strong> para o <strong>Poder Executivo ao Congresso.<\/strong><\/p>\n\n\n\n<p>A <strong>Comiss\u00e3o Mista<\/strong> de Or\u00e7amento (CMO), do Congresso Nacional, <strong>concedeu a aprova\u00e7\u00e3o<\/strong> da Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO) para <strong>2020<\/strong> no in\u00edcio de agosto. Essa Lei <strong>determina<\/strong> as <strong>metas e as prioridades<\/strong> referentes ao exerc\u00edcio do financeiro no ano seguinte.<\/p>\n\n\n\n<p>Por\u00e9m, para essa <strong>Lei entrar em vigor<\/strong> \u00e9 necess\u00e1rio que seja votada em uma sess\u00e3o conjunta no Congresso Nacional, para s\u00f3 depois ser <strong>encaminhada<\/strong> para a<strong> aprova\u00e7\u00e3o<\/strong> do Presidente Jair Bolsonaro.<\/p>\n\n\n\n<p>J\u00e1 o Projeto de <strong>Lei Or\u00e7ament\u00e1ria Anual (PLOA)<\/strong>, j\u00e1 foi encaminhado ao Congresso no <strong>\u00faltimo dia 30 de agosto.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2019\/09\/TCU-1024x684.jpg\" alt=\"\" class=\"wp-image-90764\" width=\"698\" height=\"466\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2019\/09\/TCU-300x200.jpg 300w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2019\/09\/TCU-1024x684.jpg 1024w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2019\/09\/TCU.jpg 2048w\" sizes=\"auto, (max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1200px) 70vw, 768px\"><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"vagas-ofertadas-no-concurso-tcu\">Vagas ofertadas no concurso TCU<\/h2>\n\n\n\n<p>No <strong>PLOA<\/strong>, h\u00e1 a men\u00e7\u00e3o de <strong>32 mil vagas<\/strong> para provimento em <strong>cargos p\u00fablicos <\/strong>dos Poderes Executivo, Judici\u00e1rio e Legislativo, sendo <strong>30 vagas destinadas<\/strong> para o Concurso do Tribunal de Contas da Uni\u00e3o (TCU). O documento <strong>entrar\u00e1 em vigor<\/strong>, ap\u00f3s ser<strong> votado <\/strong>em uma sess\u00e3o conjunta no Congresso e ser encaminhado para a <strong>aprova\u00e7\u00e3o <\/strong>do Presidente Jair Bolsonaro.<\/p>\n\n\n\n<p>Al\u00e9m disso, o \u00f3rg\u00e3o ir\u00e1<strong> analisar a disponibilidade or\u00e7ament\u00e1ria<\/strong> para a realiza\u00e7\u00e3o do <strong>novo certame<\/strong>. A sele\u00e7\u00e3o foi confirmada pelo Presidente da corpora\u00e7\u00e3o, Ministro Jos\u00e9 Mucio Monteiro, durante uma sess\u00e3o plen\u00e1ria realizada em agosto.<\/p>\n\n\n\n<p>No pr\u00f3ximo ano, o \u00f3rg\u00e3o possuir\u00e1 um <strong>or\u00e7amento<\/strong> de <strong>R$ 2.235 bilh\u00f5es.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2019\/09\/imagem-1.png\" alt=\"\" class=\"wp-image-92120\" width=\"928\" height=\"79\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2019\/09\/imagem-1-300x26.png 300w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2019\/09\/imagem-1.png 792w\" sizes=\"auto, (max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1200px) 70vw, 768px\"><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-340-cargos-vagos-no-tribunal\">H\u00e1 340 cargos vagos no Tribunal<\/h2>\n\n\n\n<p>H\u00e1 uma expectativa, que seja ofertada <strong>vagas para os cargos de T\u00e9cnico e Auditor<\/strong>, pois existe um grande n\u00famero de <strong>vac\u00e2ncia<\/strong> nessas carreiras no \u00f3rg\u00e3o. Recentemente, h\u00e1 mais de<strong> 340 cargos vagos<\/strong>, de acordo com o Portal de Transpar\u00eancia, o \u00f3rg\u00e3o apresenta <strong>154 vagas para Auditor de Controle Externo <\/strong>e <strong>188 para T\u00e9cnico Federal de Controle Externo.<\/strong><\/p>\n\n\n\n<p>O cargo de <strong>Auditor <\/strong>tem como requisito possuir o <strong>n\u00edvel superior<\/strong>. Do total de cargos vagos, <strong>140 <\/strong>s\u00e3o da \u00c1rea de Controle Externo e as <strong>demais vagas<\/strong> s\u00e3o para as <strong>carreiras<\/strong> de Apoio T\u00e9cnico e Administrativo (01), Enfermagem (01), Tecnologia da Informa\u00e7\u00e3o (08), Medicina (03) e Nutri\u00e7\u00e3o (01).<\/p>\n\n\n\n<p>J\u00e1 a carreira de <strong>T\u00e9cnico<\/strong>, \u00e9 necess\u00e1rio possuir <strong>n\u00edvel m\u00e9dio<\/strong>. Os <strong>cargos vagos s\u00e3o <\/strong>para as T\u00e9cnicas Administrativa (108) e de Controle Externo (56), al\u00e9m disso h\u00e1 <strong>cargos vagos<\/strong> nas seguintes <strong>carreiras<\/strong>: T\u00e9cnica Operacional (21), Tecnologia da Informa\u00e7\u00e3o (01) e Enfermagem (02).<\/p>\n\n\n\n<p>Para o <strong>cargo de Auditor<\/strong>, a <strong>validade<\/strong> do \u00faltimo certame <strong>encerrou em 2017<\/strong>. O prazo foi de <strong>06 meses<\/strong>, podendo ser prorrogado por igual per\u00edodo. J\u00e1 para <strong>T\u00e9cnicos<\/strong>, a expira\u00e7\u00e3o do \u00faltimo concurso<strong> era de dois anos<\/strong>, podendo ser prorrogado por igual per\u00edodo. O <strong>prazo <\/strong>ser\u00e1 encerrado em <strong>dezembro deste ano.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2015\/06\/tcu1.jpg\" alt=\"\" class=\"wp-image-22620\" width=\"732\" height=\"482\" loading=\"lazy\" title=\"\" srcset=\"https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2015\/06\/tcu1-300x198.jpg 300w, https:\/\/www.novaconcursos.com.br\/portal\/wp-content\/uploads\/2015\/06\/tcu1.jpg 800w\" sizes=\"auto, (max-width: 480px) 100vw, (max-width: 768px) 100vw, (max-width: 1200px) 70vw, 768px\"><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"remunerao-do-concurso-tcu\">Remunera\u00e7\u00e3o do\nconcurso TCU<\/h2>\n\n\n\n<p>Atualmente, a <strong>remunera\u00e7\u00e3o para o cargo de Auditor<\/strong> \u00e9 de <strong>R$ 17.371,38<\/strong>, j\u00e1 incluso o sal\u00e1rio base de R$ 6.635,29, Gratifica\u00e7\u00e3o de Desempenho no valor de R$ 8.475,69, aux\u00edlio-alimenta\u00e7\u00e3o de R$ 1.011,04 e aux\u00edlio-transporte no valor de R$ 1.249,61.<\/p>\n\n\n\n<p>J\u00e1 para as carreiras de <strong>T\u00e9cnicos<\/strong> os sal\u00e1rios s\u00e3o de <strong>R$ 12.548,03<\/strong>, j\u00e1 incluso o sal\u00e1rio base de R$ 4.778,15, Gratifica\u00e7\u00e3o de Desempenho de R$ 5.509,23, aux\u00edlio-alimenta\u00e7\u00e3o e aux\u00edlio transporte s\u00e3o os mesmos <strong>valores do Auditor.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ltimo-concurso-tcu\">\u00daltimo concurso\nTCU<\/h2>\n\n\n\n<p>O \u00faltimo concurso, <strong>ocorreu em 2015<\/strong>, sendo ofertadas <strong>108 vagas <\/strong>para <strong>T\u00e9cnicos (42) e Auditores (66), <\/strong>destinadas para <strong>n\u00edveis m\u00e9dio e superior<\/strong>. A banca organizadora foi o <strong>Cebraspe (Cespe\/UnB)<\/strong>.<\/p>\n\n\n\n<p>Todos os candidatos foram <strong>submetidos a provas objetivas e discursivas, <\/strong>sendo cobrado os seguintes <strong>conte\u00fados:<\/strong><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">T\u00e9cnico:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Conhecimentos B\u00e1sicos:<\/strong> L\u00edngua Portuguesa, Direito Constitucional, No\u00e7\u00f5es de Inform\u00e1tica e Atualidades;<\/li><li><strong>Conhecimentos Espec\u00edficos:<\/strong> Direito Administrativo, Execu\u00e7\u00e3o Or\u00e7ament\u00e1ria e Financeira, Controle Externo e No\u00e7\u00f5es de Administra\u00e7\u00e3o.<\/li><\/ul><h4 class=\"wp-block-heading\">Auditor:<\/h4>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Conhecimentos B\u00e1sicos:<\/strong> L\u00edngua Portuguesa, L\u00edngua Inglesa, Racioc\u00ednio Anal\u00edtico, Matem\u00e1tica Financeira, No\u00e7\u00f5es de Estat\u00edstica, Controle Externo, Direito Constitucional, Direito Administrativo, Direito Civil, Direito Processual Civil, Direito Penal, Auditoria Governamental e An\u00e1lise de Informa\u00e7\u00f5es;<\/li><li><strong>Auditoria Governamental (Conhecimentos Espec\u00edficos):<\/strong> No\u00e7\u00f5es de Economia do Setor P\u00fablico e da Regula\u00e7\u00e3o, Contabilidade e Administra\u00e7\u00e3o Financeira e Or\u00e7ament\u00e1ria;<\/li><li><strong>Auditoria de Tecnologia da Informa\u00e7\u00e3o (Conhecimentos Espec\u00edficos): <\/strong>Gest\u00e3o, Governan\u00e7a de TI e Engenharia de Software, Desenvolvimento de Sistemas, Infraestrutura de TI, Seguran\u00e7a da Informa\u00e7\u00e3o e Fiscaliza\u00e7\u00e3o de Contratos de Tecnologia da Informa\u00e7\u00e3o.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>O Concurso TCU (Tribunal de Contas da Uni\u00e3o), dever\u00e1 ser autorizado pelo Congresso Nacional ap\u00f3s a aprova\u00e7\u00e3o da Lei de Diretrizes Or\u00e7ament\u00e1rias (LDO). H\u00e1 uma previs\u00e3o que seja ofertada 30 vagas em 2020. \u21d2 Confira todas as informa\u00e7\u00f5es na p\u00e1gina do concurso! Situa\u00e7\u00e3o atual do concurso TCU De acordo com a Assessoria de Imprensa do [&hellip;]<\/p>\n","protected":false},"author":16,"featured_media":90781,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[228],"tags":[],"class_list":["post-92119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/92119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/comments?post=92119"}],"version-history":[{"count":5,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/92119\/revisions"}],"predecessor-version":[{"id":92130,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/posts\/92119\/revisions\/92130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media\/90781"}],"wp:attachment":[{"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/media?parent=92119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/categories?post=92119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.novaconcursos.com.br\/portal\/wp-json\/wp\/v2\/tags?post=92119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}